{"id":6917,"date":"2017-06-10T21:24:20","date_gmt":"2017-06-10T19:24:20","guid":{"rendered":"http:\/\/www.heusenstaemmchen.de\/blog\/?p=6917"},"modified":"2024-12-30T16:23:40","modified_gmt":"2024-12-30T15:23:40","slug":"einmal-kran-fahren","status":"publish","type":"post","link":"https:\/\/www.heusenstaemmchen.de\/news\/einmal-kran-fahren\/6917","title":{"rendered":"Einmal Kran fahren"},"content":{"rendered":"<p>Viele kleine Jungs haben sich schon einmal gew\u00fcnscht, ein gro\u00dfes Fahrzeug zu steuern. Normalerweise werden in einem solchen Fall B\u00fccher \u00fcber Baufahrzeuge, die Feuerwehr oder die Polizei verschlungen. &mdash; Habe ich noch etwas vergessen?<\/p>\n<p>Als Justin am 29. Mai hinter Autohaus Zeiger eine Baustelle entdeckte, musste er nat\u00fcrlich wieder einmal stoppen und den Bauarbeitern ein Loch in den Bauch fragen. Doch an diesem Tag war es anders als sonst. Dieses Mal durfte er sich den Kran von innen anschauen. Justin wurde von den Profis kurz die Steuerung erkl\u00e4rt, und anschlie\u00dfend durfte er sogar im Kran dabei sein, als schwere Platten bewegt wurden. <\/p>\n<p>Ein paar Tage sp\u00e4ter durfte Justin dann auch mal einen Bagger fahren, und ihm wurde gezeigt, wie man mit einem Presslufthammer umgeht. Diese Erlebnisse werden noch lange in Erinnerung bleiben. \ud83d\ude42<\/p>\n<p>Wir m\u00f6chten uns hiermit noch einmal herzlich bei den Bauarbeitern f\u00fcr diese sch\u00f6nen Stunden bedanken.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Viele kleine Jungs haben sich schon einmal gew\u00fcnscht, ein gro\u00dfes Fahrzeug zu steuern. Normalerweise werden in einem solchen Fall B\u00fccher \u00fcber Baufahrzeuge, die Feuerwehr oder die Polizei verschlungen. &mdash; Habe ich noch etwas vergessen? Als Justin am 29. Mai hinter Autohaus Zeiger&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":6961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[4,482],"class_list":["post-6917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv","tag-heusenstamm","tag-kran"],"_links":{"self":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/posts\/6917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/comments?post=6917"}],"version-history":[{"count":3,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/posts\/6917\/revisions"}],"predecessor-version":[{"id":13378,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/posts\/6917\/revisions\/13378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/media\/6961"}],"wp:attachment":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/media?parent=6917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/categories?post=6917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/tags?post=6917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}