{"id":12755,"date":"2024-04-21T17:36:27","date_gmt":"2024-04-21T15:36:27","guid":{"rendered":"https:\/\/www.heusenstaemmchen.de\/news\/?page_id=12755"},"modified":"2026-01-24T10:52:50","modified_gmt":"2026-01-24T09:52:50","slug":"polizeieinsaetze-offenbach-am-main","status":"publish","type":"page","link":"https:\/\/www.heusenstaemmchen.de\/news\/polizeieinsaetze-offenbach-am-main","title":{"rendered":"Polizeieins\u00e4tze im Kreis Offenbach heute"},"content":{"rendered":"<p><b>Aktuelle <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/polizeieinsaetze-offenbach-am-main\">Polizeieins\u00e4tze<\/a> im Kreis Offenbach am Main von heute und den letzten Wochen<\/b><\/p>\n<div><span class=\"my_article_details\"><a href=\"https:\/\/www.heusenstaemmchen.de\/news\/betrugsfaelle-offenbach-am-main\">Betrugsf\u00e4lle<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/braende-offenbach-am-main\">Br\u00e4nde<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/diebstaehle-offenbach-am-main\">Diebst\u00e4hle<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/einbrueche-offenbach-am-main\">Einbr\u00fcche<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/raubueberfaelle-offenbach-am-main\">Raub\u00fcberf\u00e4lle<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/unfaelle-offenbach-am-main\">Unf\u00e4lle<\/a><\/span><\/div>\n<p>&nbsp;<\/p>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"6fd17523\" href=\"https:\/\/of-news.de\/muehlheim\/nach-betrug-mit-bitcoin-anlagen-22-jaehriger-bei-gelduebergabe-in-muehlheim-gestoppt-168963\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf of-news.de\" target=\"_blank\">Nach Betrug mit Bitcoin-Anlagen: 22-J\u00e4hriger bei Geld\u00fcbergabe in M\u00fchlheim gestoppt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/of-news.de\/muehlheim\/nach-betrug-mit-bitcoin-anlagen-22-jaehriger-bei-gelduebergabe-in-muehlheim-gestoppt-168963\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/of-news.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   In einem umfangreichen Ermittlungsverfahren um manipulierte Geldinvestitionen hat die Kriminalpolizei am Montagnachmittag in M&uuml;hlheim am Main einen Tatverd&auml;chtigen festgenommen. Der 22-j&auml;hrige Mann war dabei, mehrere tausend Euro Bargeld von einer B&uuml;rgerin ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-14\">14.07.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/of-news.de\/muehlheim\/nach-betrug-mit-bitcoin-anlagen-22-jaehriger-bei-gelduebergabe-in-muehlheim-gestoppt-168963\/\" title=\"Link zum Artikel auf of-news.de\" target=\"_blank\">of-news.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"4f326c3f\" href=\"https:\/\/www.fr.de\/rhein-main\/offenbach\/wohnungseinbruch-in-heusenstamm-taeter-duo-fluechtet-zr-94397038.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf fr.de\" target=\"_blank\">Hochwertige Beute nach Wohnungseinbruch: Polizei ver\u00f6ffentlicht Lichtbild \u2013 wer kennt diesen Mann?<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.fr.de\/rhein-main\/offenbach\/wohnungseinbruch-in-heusenstamm-taeter-duo-fluechtet-zr-94397038.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.fr.de\/assets\/images\/43\/340\/43340040-die-polizei-fahndet-nach-diesem-mann-wer-hinweise-geben-kann-wird-gebeten-sich-mit-den-beamten-in-verbindung-zu-setzen-2Gef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   In Heusenstamm brechen zwei Unbekannte in ein Einfamilienhaus ein und stehlen hochwertige Gegenst&auml;nde im Wert von mehreren zehntausend Euro. Wer kann Hinweise zu den T&auml;tern geben?<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-14\">14.07.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.fr.de\/rhein-main\/offenbach\/wohnungseinbruch-in-heusenstamm-taeter-duo-fluechtet-zr-94397038.html\" title=\"Link zum Artikel auf fr.de\" target=\"_blank\">fr.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"6f7cb3de\" href=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/stadtpolizei-prostitutionskontrollen-in-dreieich\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf dreieich.de\" target=\"_blank\">Stadtpolizei: Prostitutionskontrollen in Dreieich<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/stadtpolizei-prostitutionskontrollen-in-dreieich\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/stadtpolizei-prostitutionskontrollen-in-dreieich\/img-4949.jpg?cid=1r69.8f14&resize=d47092%3a1024x768c\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die Stadtpolizei Dreieich hat Kontrollen gem&auml;&szlig; dem Prostituiertenschutzgesetz (ProstSchG) im Stadtgebiet durchgef&uuml;hrt und dabei vier Frauen festgestellt, die unzul&auml;ssigerweise der Prostitution nachgingen. Ausschlaggebend hierf&uuml;r ist die Lage der Stadt Dreieich ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-14\">14.07.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/stadtpolizei-prostitutionskontrollen-in-dreieich\/\" title=\"Link zum Artikel auf dreieich.de\" target=\"_blank\">dreieich.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"0b8ddedb\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 14.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Einbruchsversuch schlug fehl: Polizei bittet um Hinweise - Offenbach<\/b>   (me) Ein Unbekannter, der sich am Montag, gegen 17 Uhr, widerrechtlich Zugang zu einer Wohnung eines Mehrparteienhauses in der Stra\u00dfe \"Hafeninsel\" (10er-Hausnummern) verschaffen wollte, scheiterte an der T\u00fcr und musste wieder seines Weges ziehen.  Der T\u00e4ter ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Verdacht der gef\u00e4hrlichen K\u00f6rperverletzung: Zeugen gesucht! - Offenbach<\/b>   (me) Am Sonntagmittag soll es in der Stra\u00dfe \"Starkenburgring\" (70er-Hausnummern) zu einer handfesten Auseinandersetzung zwischen drei M\u00e4nnern gekommen sein, in deren Verlauf ein Duo einen 53-J\u00e4hrigen geschlagen und getreten haben soll. Die Ordnungsh\u00fcter des ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Fahrzeuge aufgebrochen: Polizei ermittelt - Obertshausen \/ Seligenstadt<\/b>   (me) In Obertshausen in der August-Bebel-Stra\u00dfe (einstellige Hausnummern) und in Seligenstadt in der Klein-Welzheimer Stra\u00dfe (einstellige Hausnummern) wurden zwischen Sonntag und Montag zwei Fahrzeuge aufgebrochen; nach den bisherigen Erkenntnissen wurde ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Mutma\u00dflicher Ladendieb hatte offene Haftbefehle: Einlieferung in JVA - Dreieich<\/b>   (fg) Er habe mehrere Parfum-Flaschen aus einer Auslage genommen und den Kassenbereich passiert, ohne die Ware zu bezahlen. Ein Ladendetektiv stellte am Montagnachmittag, kurz vor 13 Uhr, einen 49-J\u00e4hrigen beim Verlassen eines Drogeriemarktes in der Robert-Bosch-Stra\u00dfe ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. E-Scooter-Fahrer und Zeugen nach Sturz von Radler gesucht - Seligenstadt<\/b>   (me) Am Sonntag, gegen 21.15 Uhr, st\u00fcrzte ein Radfahrer auf dem Mainradweg und zog sich hierbei eine Fraktur des Armes zu. Urs\u00e4chlich hierf\u00fcr soll ein noch unbekannter Lenker eines E-Scooters gewesen sein, der offenbar zun\u00e4chst hinter dem Biker herfuhr, diesen ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-14\">14.07.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314410\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"32cd6387\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314435\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 14.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314435\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>Bev\u00f6lkerung versprechen.  Die Staatsanwaltschaft und die Polizei fragen nun:     - Wer kann Hinweise zu der abgebildeten Person geben?<\/b>   -  ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314435\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>Wer hat diese Personen auf der Flucht beobachtet?    - Wo sind die T\u00e4ter vielleicht noch aufgefallen?<\/b>   - Sind die Unbekannten m\u00f6glicherweise in ein Fahrzeug gestiegen       oder haben ein anderes Fluchtmittel benutzt?  Zeugen werden gebeten, sich unter der Rufnummer 069 8098-1234 mit den Ermittlern aus Offenbach in Verbindung zu setzen.  Hinweis: Dieser Meldung ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-14\">14.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314435\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"c6c7c415\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 14.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>Meldung sind bitte an die gemeinsame Pressestelle der Staatsanwaltschaft Darmstadt - Zweigstelle Offenbach, E-Mail:<\/b> pressestelle@sta-darmstadt.justiz.hessen.de , zu richten.  PR\u00c4VENTIONSHINWEISE  Cybertrading-Betrug: Polizei warnt vor Gefahr im Internet Die Polizei warnt eindringlich vor der immer wiederkehrender Betrugsmasche im Internet: dem sogenannten Cybertrading-Betrug ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>Unrealistisch hohe Gewinnversprechen oder angeblich risikofreie       Anlagen    - Prominente, die vermeintlich f\u00fcr Investments werben<\/b>   -  ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>Broker    - Aufforderung zur Installation von Fernzugriffssoftware    - Fehlende oder unklare Unternehmensangaben<\/b>  ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>Verhaltensempfehlungen:     - Werbung kritisch hinterfragen und eigenst\u00e4ndig \u00fcberpr\u00fcfen    - Keine Fernwartungssoftware installieren<\/b>   -  ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>Keine sensiblen Daten wie Ausweiskopien oder Bankinformationen       weitergeben    - Vor Investitionen unabh\u00e4ngige Beratung einholen<\/b>   - Im Zweifel keine Zahlungen leisten  Wer Zweifel hat oder bereits betroffen ist, sollte sich umgehend an die Polizei wenden.  Weitere Informationen sind unter nachfolgendem Link zu finden:  https:\/\/www.polizei.hessen.de\/praevention\/gemeinsam-sicher-in-hessen\/sicher-im-internet\/online-trading ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-14\">14.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6314550\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"17be86a7\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/13\/blitzer-im-kreis-offenbach-und-main-kinzig-kreis-82\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Blitzer im Kreis Offenbach und Main-Kinzig-Kreis<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/13\/blitzer-im-kreis-offenbach-und-main-kinzig-kreis-82\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die Beamtinnen und Beamten der Verkehrsdirektion kontrollieren in der n&auml;chsten Woche die Einhaltung der Tempolimits unter anderem an Unfallschwerpunkten. Geplant sind Messungen im Bereich folgender &Ouml;rtlichkeiten: 13.07.2026: Bruchk&ouml;bel, Landesstra&szlig;e 3347 (Unfallschwerpunkt). ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-13\">13.07.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/13\/blitzer-im-kreis-offenbach-und-main-kinzig-kreis-82\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"f6a4d2f7\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313395\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Vermisstenfahndung nach Katharina Marino<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313395\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   F\u00fcrth (Odenwald)\/Stadt und Landkreis Offenbach  (ots)      (me) Anbei wird auf die Pressemeldung des Polizeipr\u00e4sidiums S\u00fcdhessen verwiesen.  Die Polizei bittet die Bev\u00f6lkerung bei der Suche nach der 13-j\u00e4hrigen Katharina Marino um Mithilfe.  Die Jugendliche ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-13\">13.07.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313395\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"5253dbb6\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 13.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. F\u00fchrerschein beschlagnahmt, BMW sichergestellt: Zeugensuche! - Offenbach<\/b>   (fg) Wegen des Verdachts eines verbotenen Kraftfahrzeugrennens sowie der Gef\u00e4hrdung des Stra\u00dfenverkehrs muss sich seit Samstagabend ein 20 Jahre alter BMW-Fahrer verantworten. Zivile Einsatzkr\u00e4fte des Sachgebiets \"Tuner, Raser und Poser\" nahmen den mutma\u00dflichen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Trunkenheitsfahrt mit mehr als drei Promille, Sicherstellung eines E-Scooters und weitere Strafanzeigen - Offenbach<\/b>   (fg) Im Rahmen gezielter Kontrollen im Stadtgebiet hat die Polizei in der Nacht zum Samstag mehrere Straftaten und auch Ordnungswidrigkeiten festgestellt. Die Ordnungsh\u00fcter registrierten unter anderem eine Trunkenheitsfahrt mit mehr als drei Promille, leiteten ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Bargeld bei Einbruch in Friseursalon geklaut - Offenbach<\/b>   (me) \u00dcber 5.000 Euro Bargeld erbeutete ein unbekannter Langfinger bei einem Einbruch in einen Friseursalon. Die Polizei erhielt am Samstagmorgen Kenntnis von dem Geschehen und nahm umgehend die Ermittlungen auf. Nach den bisherigen Erkenntnissen drang der ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Festnahme eines 25-J\u00e4hrigen: Ermittlungen wegen des Verdachts der Erregung \u00f6ffentlichen \u00c4rgernisses - Offenbach<\/b>   (fg) Polizeibeamte nahmen am Sonntagmorgen, kurz nach 9.30 Uhr, einen 25-J\u00e4hrigen in der Geleitsstra\u00dfe nahe einer dortigen Kirche (100er-Hausnummern) vorl\u00e4ufig fest und ermitteln nun wegen des Verdachts der Erregung \u00f6ffentlichen \u00c4rgernisses gegen den Wohnsitzlosen. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. 17-J\u00e4hriger bei Zusammensto\u00df schwer verletzt - Rodgau<\/b>   (me) Die Beamten aus Heusenstamm suchen nach Zeugen eines Verkehrsunfalls von Samstagnachmittag. Gegen 17.35 Uhr soll es auf der Rodgau-Ring-Stra\u00dfe zu einem Zusammensto\u00df im Bereich eines dortigen Zebrastreifens gekommen sein. Nach den bisherigen Erkenntnissen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Ringe und Uhren aus Hochhaus gestohlen: Zeugen gesucht! - Dietzenbach<\/b>   (fg) Unbekannte sind am vergangenen Wochenende in eine Wohnung eines Hochhauses in der Dreieichstra\u00dfe (30er-Hausnummern) eingebrochen und haben mehrere Ringe sowie Uhren gestohlen. Die Tat ereignete sich zwischen Freitagmorgen, 3 Uhr und Sonntagvormittag, ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Betr\u00fcger erbeuteten Schmuck und EC-Karte - Egelsbach<\/b>   (me) Hochwertigen Schmuck und andere Accessoires erbeuteten Betr\u00fcger im Verlauf des Freitags, weshalb die Polizei umgehend Ermittlungen eingeleitet hat. Gegen 12 Uhr erhielt eine Seniorin aus der Schafhofstra\u00dfe einen Anruf von einem angeblichen Polizeibeamten. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>8. Geparkter Hyundai touchiert: Zeugensuche der Polizei - Seligenstadt<\/b>   (me) Ein Schaden von mehreren hundert Euro entstand am Freitagvormittag an einem geparkten Hyundai, nachdem ein noch unbekannter Wagenlenker mit seinem offenbar ebenfalls blauen Wagen gegen diesen gefahren war. Gegen 10.45 Uhr soll es zu dem Zusammensto\u00df ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>9. Meinungsverschiedenheit im Stra\u00dfenverkehr uferte aus - Hainburg<\/b>   (me) Eine \"genommene\" Vorfahrt war scheinbar der Grund f\u00fcr eine Meinungsverschiedenheit zwischen einem Wagenlenker und dem Fahrer eines Leichtkraftrads, welche in einer handfesten Auseinandersetzung endete. Die Polizei ermittelt nun wegen des Verdachts der ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-13\">13.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/egelsbach-aktuell\" title=\"Egelsbach heute aktuell\">Egelsbach<\/a> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6313436\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2e6e093b\" href=\"https:\/\/ffhstm.de\/aktuelles#3\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf ffhstm.de\" target=\"_blank\">2.500 m\u00b2 Waldfl\u00e4che in Flammen am Samstagabend \u2013 Schwierige L\u00f6scharbeiten, zwei Feuerwehrleute verletzt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/ffhstm.de\/aktuelles#3\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/ffhstm.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Am Samstagabend (11. Juli 2026) wurden die Heusenstammer Feuerwehren um 21:07 Uhr zu einer Rauchentwicklung aus dem Waldgebiet hinter dem Wohngebiet Am Goldberg im Heusenstammer Osten alarmiert. Bereits auf der Anfahrt der ersten Kr\u00e4fte wies eine gro\u00dfe Rauchwolke ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-12\">12.07.2026<\/time> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/ffhstm.de\/aktuelles#3\" title=\"Link zum Artikel auf ffhstm.de\" target=\"_blank\">ffhstm.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"484676a6\" href=\"https:\/\/ffhstm.de\/aktuelles#2\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf ffhstm.de\" target=\"_blank\">Feuerwehr: Feuer in einem Wohngeb\u00e4ude am Sonntagnachmittag \u2013 keine Verletzten<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/ffhstm.de\/aktuelles#2\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/ffhstm.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die hohe Belastung der ehrenamtlichen Einsatzkr\u00e4fte der Schlossstadt rei\u00dft nicht ab. Am Sonntagnachmittag (12. Juli 2026) kam es um 17:42 Uhr zu einem Feuer in einem Anbau eines Wohnhauses in der B\u00fcrgermeister-K\u00e4mmerer-Stra\u00dfe und machte den Einsatz des L\u00f6schzugs ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-12\">12.07.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/ffhstm.de\/aktuelles#2\" title=\"Link zum Artikel auf ffhstm.de\" target=\"_blank\">ffhstm.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"49f14139\" href=\"https:\/\/fledermausschutz-seligenstadt.de\/erfolgreiche-stockentenbrut-im-schwimmbad-in-seligenstadt\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf fledermausschutz-seligenstadt.de\" target=\"_blank\">Naturschutz: Erfolgreiche Stockentenbrut im Schwimmbad in Seligenstadt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   Vor knapp zwei Wochen meldet sich die UNB bei uns wegen einer Stockentenbrut am Beckenrand im Schwimmbad. Mit den Bademeistern wurde die Sitution besprochen und wir einigten uns darauf die Brut weiterlaufen zu lassen. Ich w&uuml;rde nach dem Schlupf der K&uuml;cken benachrichtigt. ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-11\">11.07.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <\/span><a href=\"https:\/\/fledermausschutz-seligenstadt.de\/erfolgreiche-stockentenbrut-im-schwimmbad-in-seligenstadt\/\" title=\"Link zum Artikel auf fledermausschutz-seligenstadt.de\" target=\"_blank\">fledermausschutz-seligenstadt.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"background-color: #e6e6ff; margin-bottom: 40px; padding: 10px;\"><article><a style=\"color: #000000; font-size: 20px; font-weight: normal; text-decoration: underlined;\" href=\"https:\/\/www.ndr.de\/nachrichten\/info\/solarenergie-liefert-erstmals-mehr-strom-als-aus-braunkohle,photovoltaik-124.html\" target=\"_blank\">Solarenergie liefert erstmals mehr Strom als Braunkohle<\/a><\/p><div class=\"entry\"><p style=\"margin-bottom: 4px;\"><a href=\"https:\/\/www.ndr.de\/nachrichten\/info\/solarenergie-liefert-erstmals-mehr-strom-als-aus-braunkohle,photovoltaik-124.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"align: left !important; float: left !important; margin-top: 4px !important; margin-right: 8px !important; margin-bottom: 4px !important; width: 90px !important;\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.heusenstaemmchen.de\/feeds\/gfx\/ndr.de.png\" \/><\/a>Photovoltaik lag vergangenes Jahr zum ersten Mal auf Platz 2 bei der Stromerzeugung in Deutschland &#8211; vor Braunkohle und Erdgas. Insgesamt stieg der Anteil erneuerbarer Energien am Strommix aber nicht.<br clear=\"all\" \/><\/p><div><b>Schon gewusst?<\/b> \u00b7 Regenerative Energien \u00b7 <a title=\"Mehr Details auf ndr.de\" href=\"https:\/\/www.ndr.de\/nachrichten\/info\/solarenergie-liefert-erstmals-mehr-strom-als-aus-braunkohle,photovoltaik-124.html\" target=\"_blank\" rel=\"noopener\">ndr.de<\/a><\/div><\/div><\/article><\/div><div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"ec2915e3\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/mutmassliche-sprayer-in-seligenstadt-vorlaeufig-festgenommen\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Mutma\u00dfliche Sprayer in Seligenstadt vorl\u00e4ufig festgenommen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/mutmassliche-sprayer-in-seligenstadt-vorlaeufig-festgenommen\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Auf rund 6.000 Euro wird der Schaden gesch&auml;tzt, den zwei Jugendliche am Donnerstagabend in einem Parkhaus in der Palatiumstra&szlig;e in Seligenstadt verursacht haben sollen. Gegen die beiden Jugendlichen wird nun wegen des Verdachts der Sachbesch&auml;digung durch Graffiti ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-10\">10.07.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/mutmassliche-sprayer-in-seligenstadt-vorlaeufig-festgenommen\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"8976116b\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/einige-interessante-einsaetze-der-stadtpolizei-offenbach-im-juni\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Einige interessante Eins\u00e4tze der Stadtpolizei Offenbach im Juni<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/einige-interessante-einsaetze-der-stadtpolizei-offenbach-im-juni\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Der Juni startete f&uuml;r die Stadtpolizei Offenbach mit einer Gefahrgutkontrolle, bei der 35 Fahrzeuge und Fahrer in Augenschein genommen wurden. Darunter ein rauchender Fahrer, der Gasflaschen transportierte. Im Laufe des Monats gab es mehrere Eins&auml;tze, um Tieren ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-10\">10.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/einige-interessante-einsaetze-der-stadtpolizei-offenbach-im-juni\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"1f8081ad\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/polizeibeamte-nach-inobhutnahme-zweier-kinder-in-offenbach-im-einsatz-verletzt\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Polizeibeamte nach Inobhutnahme zweier Kinder in Offenbach im Einsatz verletzt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/polizeibeamte-nach-inobhutnahme-zweier-kinder-in-offenbach-im-einsatz-verletzt\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Polizeibeamte waren am Donnerstagnachmittag im Rahmen der Inobhutnahme zweier Kinder in Amtshilfe f&uuml;r das Jugendamt der Stadt Offenbach in der Bettinastra&szlig;e im Einsatz. Hintergrund der Ma&szlig;nahme war der Verdacht einer akuten Kindeswohlgef&auml;hrdung. Aufgrund vorliegender ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-10\">10.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/polizeibeamte-nach-inobhutnahme-zweier-kinder-in-offenbach-im-einsatz-verletzt\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"a5e2fb6c\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/ermittlungen-wegen-verstoss-gegen-das-waffengesetz-vorlaeufige-festnahme-in-offenbach\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Ermittlungen wegen Versto\u00df gegen das Waffengesetz: Vorl\u00e4ufige Festnahme in Offenbach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/ermittlungen-wegen-verstoss-gegen-das-waffengesetz-vorlaeufige-festnahme-in-offenbach\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Polizeibeamte machten am Mittwochnachmittag einen Verd&auml;chtigen in einer Wohnung in der Bl&uuml;cherstra&szlig;e in Offenbach ausfindig, stellten im weiteren Verlauf eine Schreckschusswaffe samt Zubeh&ouml;r sicher und ermitteln nun wegen des Verdachts des Versto&szlig;es gegen das ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-10\">10.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/10\/ermittlungen-wegen-verstoss-gegen-das-waffengesetz-vorlaeufige-festnahme-in-offenbach\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"998caf0a\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6312056\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 10.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6312056\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Mutma\u00dfliche Sprayer vorl\u00e4ufig festgenommen: Ermittlungen eingeleitet - Seligenstadt<\/b>   (fg) Auf rund 6.000 Euro wird der Schaden gesch\u00e4tzt, den zwei Jugendliche am Donnerstagabend in einem Parkhaus in der Palatiumstra\u00dfe verursacht haben sollen. Gegen die beiden Jugendlichen wird nun wegen des Verdachts der Sachbesch\u00e4digung durch Graffiti ermittelt. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6312056\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Fahrradcodieraktionen der Schutzfrau vor Ort waren voller Erfolg - Seligenstadt<\/b>   (fg) Polizeioberkommissarin Lisa Spitz, Schutzfrau vor Ort der Polizeistation Seligenstadt, f\u00fchrte am Montag und Dienstag zwei Fahrradcodierungsaktion durch. In der Zeit von jeweils 10 bis 14 Uhr konnten B\u00fcrgerinnen und B\u00fcrger ihre Fahrr\u00e4der auf dem Gel\u00e4nde ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-10\">10.07.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6312056\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"1da5f168\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/09\/mit-e-scooter-auf-fahrrad-aufgefahren-polizei-sucht-zeugen-in-langen\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Mit E-Scooter auf Fahrrad aufgefahren: Polizei sucht Zeugen in Langen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/09\/mit-e-scooter-auf-fahrrad-aufgefahren-polizei-sucht-zeugen-in-langen\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Ein n&auml;chtlicher Heimweg endete in Langen mit einem Sturz und einem Krankenhausaufenthalt: Mutma&szlig;lich aufgrund ihrer starken Alkoholisierung soll eine 17 Jahre alte E-Scooter-Fahrerin am fr&uuml;hen Donnerstagmorgen in der Bahnstra&szlig;e auf einen vorausfahrenden Radler ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-09\">09.07.2026<\/time> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/09\/mit-e-scooter-auf-fahrrad-aufgefahren-polizei-sucht-zeugen-in-langen\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2239f879\" href=\"https:\/\/www.op-online.de\/offenbach\/fuenfstelligen-wert-einbruch-in-optikergeschaeft-diebe-nehmen-brillen-im-94389662.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Einbruch in Optikergesch\u00e4ft: Diebe nehmen Brillen im f\u00fcnfstelligen Wert<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/offenbach\/fuenfstelligen-wert-einbruch-in-optikergeschaeft-diebe-nehmen-brillen-im-94389662.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/276\/43276680-diebe-richten-in-einem-optikergeschaeft-grossen-schaden-an-symbolfoto-1gef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Brillen im Wert von mehreren zehntausend Euro haben Diebe in Offenbach aus einem Optikergesch&auml;ft gestohlen. Die Polizei sucht Zeugen des Einbruchs.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-09\">09.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/offenbach\/fuenfstelligen-wert-einbruch-in-optikergeschaeft-diebe-nehmen-brillen-im-94389662.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"48614378\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/09\/tote-person-bei-wohnungsbrand-in-offenbach-aufgefunden\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Tote Person bei Wohnungsbrand in Offenbach aufgefunden<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/09\/tote-person-bei-wohnungsbrand-in-offenbach-aufgefunden\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Am Donnerstagmorgen kam es in der Kaiserstra&szlig;e (100er-Hausnummern) in Offenbach in einem dortigen Wohnhaus zu einem Brand, bei dem eine Person in den R&auml;umlichkeiten tot aufgefunden wurde. Nach den bisherigen Erkenntnissen wurden Anwohner gegen 1.30 Uhr auf ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-09\">09.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/09\/tote-person-bei-wohnungsbrand-in-offenbach-aufgefunden\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"background-color: #f4f4f4; margin-bottom: 40px; padding: 10px;\"><article><a style=\"color: #000000; font-size: 20px; font-weight: normal; text-decoration: underlined;\" href=\"https:\/\/www.tagesschau.de\/wirtschaft\/elektroauto-kosten-strom-100.html\" target=\"_blank\">Laden von E-Autos deutlich g\u00fcnstiger als Tanken<\/a><\/p><div class=\"entry\"><p style=\"margin-bottom: 4px;\"><a href=\"https:\/\/www.tagesschau.de\/wirtschaft\/elektroauto-kosten-strom-100.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"align: left !important; float: left !important; margin-top: 4px !important; margin-right: 8px !important; margin-bottom: 4px !important; width: 90px !important;\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.heusenstaemmchen.de\/feeds\/gfx\/tagesschau.de.png\" \/><\/a>Wer ein E-Auto besitzt und das zu Hause laden kann, der war im vergangenen Jahr am g\u00fcnstigsten unterwegs. Wer \u00f6ffentliche Lades\u00e4ulen nutzte, zahlte zwar mehr, aber immer noch viel weniger als die Fahrer von Benzinern an der Tankstelle.<br clear=\"all\" \/><\/p><div><b>Schon gewusst?<\/b> \u00b7 Regenerative Energien \u00b7 <a title=\"Mehr Details auf tagesschau.de\" href=\"https:\/\/www.tagesschau.de\/wirtschaft\/elektroauto-kosten-strom-100.html\" target=\"_blank\" rel=\"noopener\">tagesschau.de<\/a><\/div><\/div><\/article><\/div><div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"a7664e4f\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311105\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Tote Person bei Wohnungsbrand aufgefunden: Ermittlungen zur Brandursache eingeleitet<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311105\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   (me) Am Donnerstagmorgen kam es in der Kaiserstra\u00dfe (100er-Hausnummern) in einem dortigen Wohnhaus zu einem Brand, bei dem eine Person in den R\u00e4umlichkeiten tot aufgefunden wurde. Nach den bisherigen Erkenntnissen wurden Anwohner gegen 1.30 Uhr auf das Feuer ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-09\">09.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311105\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"9edf36cf\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 09.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Ermittlungen wegen Versto\u00df gegen das Waffengesetz: Vorl\u00e4ufige Festnahme - Offenbach<\/b>   (fg) Polizeibeamte machten am Mittwochnachmittag einen Verd\u00e4chtigen in einer Wohnung in der Bl\u00fccherstra\u00dfe ausfindig, stellten im weiteren Verlauf eine Schreckschusswaffe samt Zubeh\u00f6r sicher und ermitteln nun wegen des Verdachts des Versto\u00dfes gegen das Waffengesetz. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Bei Einbruch in Optikgesch\u00e4ft: Brillen im Wert von mehreren zehntausend Euro erbeutet - Offenbach<\/b>   (me) In der Nacht zum Mittwoch drangen unbekannte Langfinger gewaltsam in ein Optikgesch\u00e4ft in der Herrnstra\u00dfe ein und stahlen in der Folge mehrere hochwertige Brillen. Zwischen 18.30 Uhr und 8.40 Uhr \u00fcberwanden die T\u00e4ter die T\u00fcr zum Verkaufsraum und nahmen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Goldschmuck und Bargeld aus Wohnung gestohlen: Zeugensuche! - Offenbach<\/b>   (fg) Einbrecher waren am Mittwoch, zwischen 18 Uhr und 20.30 Uhr, in einer Wohnung eines Mehrfamilienhauses im Odenwaldring (90er-Hausnummern) zugange und entwendeten Bargeld sowie Goldschmuck. Nach bisherigen Erkenntnissen hebelten die Unbekannten eine Zugangst\u00fcr ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Nach Wechselgeld gefragt, stattdessen Geldb\u00f6rse gestohlen - Zeugen gesucht! - Offenbach<\/b>   (fg) Etwa 45 Jahre alt, circa 1,65 Meter gro\u00df, kr\u00e4ftig, schwarze Haare an den Seiten rasiert; mit dieser Personenbeschreibung sucht die Polizei nach einem Dieb. Der Unbekannte sprach am Mittwochabend, gegen 19.35 Uhr, einen Passanten an und bat diesen, Euro-M\u00fcnzen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Seitent\u00fcr aufgeschnitten: Werkzeuge gestohlen - M\u00fchlheim am Main<\/b>   (fg) Unbekannte schnitten zwischen Dienstagnachmittag, 16.45 Uhr und Mittwochmorgen, 7.15 Uhr, die Seitent\u00fcr eines in der L\u00e4mmerspieler Stra\u00dfe (100er-Hausnummern) abgestellten Wagens auf und nahmen anschlie\u00dfend diversere Arbeits- sowie Schneidewerkzeuge mit. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Zwei Kupferkabelrollen von Firmengel\u00e4nde entwendet: Zeugen gesucht! - Dietzenbach<\/b>   (fg) Nach dem Diebstahl von zwei Kupferkabelrollen am Mittwochabend in der Assar-Gabrielsson-Stra\u00dfe (10er-Hausnummern) ermittelt die Polizei und sucht nach Zeugen. Nach bisherigen Erkenntnissen fand der Diebstahl zwischen 19.30 Uhr und 20.45 Uhr statt. Ein ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Mit E-Scooter auf Fahrrad aufgefahren: Polizei sucht Zeugen - Langen<\/b>   (fg) Ein n\u00e4chtlicher Heimweg endete in Langen mit einem Sturz und einem Krankenhausaufenthalt: Mutma\u00dflich aufgrund ihrer starken Alkoholisierung soll eine 17 Jahre alte E-Scooter-Fahrerin am fr\u00fchen Donnerstagmorgen in der Bahnstra\u00dfe auf einen vorausfahrenden ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-09\">09.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6311283\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"88de651e\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/zwei-tatverdaechtige-nach-einbruch-in-obertshausen-in-untersuchungshaft\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Zwei Tatverd\u00e4chtige nach Einbruch in Obertshausen in Untersuchungshaft<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/zwei-tatverdaechtige-nach-einbruch-in-obertshausen-in-untersuchungshaft\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Dank aufmerksamer Zeugen in Obertshausen nahmen herbeigeeilte Polizeibeamte am Dienstagnachmittag zwei tatverd&auml;chtige Frauen im Alter von 29 und 37 Jahren vorl&auml;ufig fest. Eine bis dato noch unbekannte Frau, die ebenfalls an dem Einbruch in ein Mehrfamilienhaus ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/zwei-tatverdaechtige-nach-einbruch-in-obertshausen-in-untersuchungshaft\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"a3962a65\" href=\"https:\/\/www.op-online.de\/region\/dietzenbach\/danach-automatensprengung-in-dietzenbach-die-bilder-vom-morgen-94387787.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Automatensprengung in Dietzenbach \u2013 die Bilder vom Morgen danach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/dietzenbach\/danach-automatensprengung-in-dietzenbach-die-bilder-vom-morgen-94387787.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/262\/43262392-unbekannte-haben-mittwochnacht-einen-geldautomaten-in-einer-sparkassenfiliale-in-dietzenbach-gesprengt-die-polizei-hat-die-ermittlungen-vor-ort-1Oef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Unbekannte haben Mittwochnacht einen Geldautomaten in einer Sparkassenfiliale in Dietzenbach gesprengt. Die Polizei hat die Ermittlungen vor Ort aufgenommen.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/dietzenbach\/danach-automatensprengung-in-dietzenbach-die-bilder-vom-morgen-94387787.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"4b066b1f\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/zeugensuche-der-polizei-nach-geldautomatensprengung-in-dietzenbach\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Zeugensuche der Polizei nach Geldautomatensprengung in Dietzenbach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/zeugensuche-der-polizei-nach-geldautomatensprengung-in-dietzenbach\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Am Mittwochmorgen nahmen Anwohner im Bereich der Stra&szlig;e &quot;Gallische Stra&szlig;e&quot; in Dietzenbach einen lauten Knall wahr und informierten folgerichtig die Polizei. Die herbeigeeilten Beamten stellten kurz darauf einen stark besch&auml;digten Innenraum der dortigen Bankfiliale ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/zeugensuche-der-polizei-nach-geldautomatensprengung-in-dietzenbach\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"ad32ac9b\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/auseinandersetzung-an-bushaltestelle-polizei-ermittelt-und-sucht-zeugen-in-offenbach\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Auseinandersetzung an Bushaltestelle: Polizei ermittelt und sucht Zeugen in Offenbach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/auseinandersetzung-an-bushaltestelle-polizei-ermittelt-und-sucht-zeugen-in-offenbach\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Nach einer Auseinandersetzung an einer Bushaltestelle in der Erich-Ollenhauer-Stra&szlig;e in Offenbach im Bereich der 30er-Hausnummern, die sich bereits am vergangenen Mittwoch , gegen 21 Uhr ereignete, ermittelt die Polizei und sucht nach wie vor nach Zeugen. Nach ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/08\/auseinandersetzung-an-bushaltestelle-polizei-ermittelt-und-sucht-zeugen-in-offenbach\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"9fcab56b\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310471\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 08.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310471\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Werkzeug und andere Arbeitsmaterialien aus Container gestohlen - Offenbach<\/b>   (me) Beute im Wert von etwa 15.000 Euro machten unbekannte Langfinger bei einem Einbruch in einen Baucontainer in der Daimlerstra\u00dfe (einstellige Hausnummern). Zwischen Montag, 17 Uhr und Dienstag, 6 Uhr, \u00f6ffneten die Eindringlinge mit einem Werkzeug die Umfriedung ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310471\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Lagerhalle mit Graffiti bespr\u00fcht: Polizei ermittelt - Heusenstamm<\/b>   (me) Unbekannte bespr\u00fchten eine in einer Feldgemarkung im Bereich der Ringstra\u00dfe \/ Nieder-R\u00f6der-Weg gelegene Scheune mit Farbe, weshalb die Polizei nun wegen des Verdachts der Sachbesch\u00e4digung durch Graffiti ermittelt. Der Schaden wird auf etwa 200 Euro beziffert. ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310471\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"33d1f8ea\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310709\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Wie sch\u00fctze ich mein Zuhause? Vortrag zum Thema \"Einbruchschutz\"<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310709\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   M\u00fchlheim am Main  (ots)      (me) Die Pr\u00e4ventionsabteilung des Polizeipr\u00e4sidiums S\u00fcdosthessen l\u00e4dt am 15. Juli zu einer Veranstaltung zum Thema \"Schutz vor Wohnungseinbr\u00fcchen - so sch\u00fctzen Sie Ihr Zuhause\" ein.  Wann: 17 Uhr bis 19 Uhr  Wo: Rathaus in M\u00fchlheim ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310709\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"background-color: #f4f4f4; margin-bottom: 40px; padding: 10px;\"><article><a style=\"color: #000000; font-size: 20px; font-weight: normal; text-decoration: underlined;\" href=\"https:\/\/www.tagesschau.de\/wirtschaft\/energie\/boom-batteriespeicher-deutschland-energiewende-100.html\" target=\"_blank\">Batteriegro\u00dfspeicher erleben einen Boom<\/a><\/p><div class=\"entry\"><p style=\"margin-bottom: 4px;\"><a href=\"https:\/\/www.tagesschau.de\/wirtschaft\/energie\/boom-batteriespeicher-deutschland-energiewende-100.html\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" style=\"align: left !important; float: left !important; margin-top: 4px !important; margin-right: 8px !important; margin-bottom: 4px !important; width: 90px !important;\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.heusenstaemmchen.de\/feeds\/gfx\/tagesschau.de.png\" \/><\/a>Um Erneuerbare Energien effizienter zu nutzen, werden Batterie&shy;gro\u00df&shy;speicher ben\u00f6tigt. F\u00fcr Experten sind sie ein entscheidender Baustein der Energiewende. Die Nachfrage ist enorm.<br clear=\"all\" \/><\/p><div><b>Schon gewusst?<\/b> \u00b7 Regenerative Energien \u00b7 <a title=\"Mehr Details auf tagesschau.de\" href=\"https:\/\/www.tagesschau.de\/wirtschaft\/energie\/boom-batteriespeicher-deutschland-energiewende-100.html\" rel=\"noopener\">tagesschau.de<\/a><\/div><\/div><\/article><\/div><div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"e5134ba7\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310796\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 08.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310796\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>Meldung sind bitte an die gemeinsame Pressestelle der Staatsanwaltschaft Darmstadt - Zweigstelle Offenbach, E-Mail:<\/b> pressestelle@sta-darmstadt.justiz.hessen.de , zu richten. ... ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-08\">08.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6310796\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"c3e2a8db\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 07.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Mutma\u00dflicher Kabeldieb vorl\u00e4ufig festgenommen - Offenbach<\/b>   (fg) Dank einer aufmerksamen Zeugin nahmen herbeigeeilte Polizeistreifen am sp\u00e4ten Montagabend, kurz nach 23 Uhr, einen mutma\u00dflichen Kabeldieb nahe einer Baustelle vorl\u00e4ufig fest. Die Zeugin meldete sich am Abend bei den Ordnungsh\u00fctern und gab an, dass zwei ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Verdacht der exhibitionistischen Handlungen: Tatverd\u00e4chtiger zeitnah festgenommen und in Fachklinik gebracht - Offenbach<\/b>   (me) Er soll sich am Montagnachmittag in der Ottersfuhrstra\u00dfe gegen\u00fcber einer Fu\u00dfg\u00e4ngerin entbl\u00f6\u00dft haben: So die Vorw\u00fcrfe gegen einen 27-J\u00e4hrigen, den die Beamten aus Offenbach zeitnah ausfindig machten und vorl\u00e4ufig festnahmen. Um kurz vor 17 Uhr soll sich ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Auseinandersetzung an Bushaltestelle: Polizei ermittelt und sucht Zeugen - Offenbach<\/b>   (fg) Nach einer Auseinandersetzung an einer Bushaltestelle in der Erich-Ollenhauer-Stra\u00dfe im Bereich der 30er-Hausnummern, die sich vergangenen Mittwoch (1. Juli 2026), gegen 21 Uhr ereignete, ermittelt die Polizei und sucht nach wie vor nach Zeugen. Nach ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Zeugensuche nach Kellereinbruch - Offenbach<\/b>   (fg) Nach einem Kellereinbruch in der Stra\u00dfe \"Hafeninsel\" (20er-Hausnummern) am fr\u00fchen Dienstagmorgen, gegen 3 Uhr, ermittelt die Kripo und bittet Zeugen, sich zu melden. Nach bisherigen Erkenntnissen verschaffte sich der T\u00e4ter zun\u00e4chst Zutritt zu dem Gemeinschaftskeller ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Polizei sucht nach Unfall weiterhin nach unbekanntem E-Scooter-Fahrer - Offenbach<\/b>   (fg) Bereits am 19. Juni (Freitagmorgen, gegen 7.50 Uhr) ereignete sich in der Bieberer Stra\u00dfe (260er-Hausnummern) ein Zusammensto\u00df zwischen einem unbekannten E-Scooter-Fahrer und einer Radfahrerin. Im Zuge der Ermittlungen wegen des unerlaubten Entfernens ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Zeugensuche nach Diebstahl von Damenr\u00e4dern - Offenbach<\/b>   (me) Am Montagmorgen, gegen 6.30 Uhr, lud ein noch unbekannter Langfinger insgesamt drei offenbar unverschlossene Fahrr\u00e4der in der Pirazzistra\u00dfe in einen Mercedes Sprinter mit ausl\u00e4ndischen Kennzeichenschildern und fuhr mit diesen in unbekannte Richtung davon. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Wei\u00dfer Golf und Fahrer nach Verkehrsunfallflucht gesucht - Offenbach<\/b>   (me) In der Hermann-Steinh\u00e4user-Stra\u00dfe (60er-Hausnummern) kam es in der Nacht zum Dienstag zu einem Verkehrsunfall mit anschlie\u00dfender Flucht des vermeintlichen Verursachers. Der Fahrer eines wei\u00dfen Golfs mit F-Kennzeichenschildern soll gegen 23 Uhr im Bereich ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>8. Offenbar keine Beute bei Einbruch - Offenbach<\/b>   (me) Drei Gauner brachen am fr\u00fchen Dienstagmorgen gewaltsam mehrere Garagentore auf und zerst\u00f6rten eine Fensterscheibe bei ihrer Suche nach brauchbarer Beute. Zuvor \u00fcberwand das zwischen 1,70 Meter und 1,85 Meter gro\u00dfe Trio den Zaun des Gel\u00e4ndes in der Von-Behring-Stra\u00dfe ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>9. Unfallflucht in der Ludwigstra\u00dfe: Polizei bittet um Hinweise - Rodgau<\/b>   (me) Am Montag, gegen 11.45 Uhr, kam es im Ortsteil J\u00fcgesheim zu einer Verkehrsunfallflucht. Ein noch unbekannter Wagenlenker, der als etwa 60 Jahre alt, grauhaarig und Brillentr\u00e4ger beschrieben werden kann, soll bei der Vorbeifahrt mit seinem wei\u00dfen Kleinwagen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>10. Mehrere Handwerkerfahrzeuge aufgebrochen - Neu-Isenburg \/ Dreieich<\/b>   (me) Die Polizei ermittelt derzeit wegen mehrerer Aufbr\u00fcche in sogenannte \"Handwerkerfahrzeuge\". Bislang sind bei den Beamten aus Neu-Isenburg f\u00fcnf solcher Taten bekannt geworden. In allen F\u00e4llen schnitten die Unbekannten die Bordwand der Wagen auf, um diese ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>11. Einbrecher waren in Seniorenwohnheim zugange: Zeugen gesucht! - Dreieich<\/b>   (fg) Auf rund 5.000 Euro wird der Schaden gesch\u00e4tzt, den Unbekannte bei einem Einbruch in die B\u00fcror\u00e4umlichkeiten eines Seniorenheims in der Taunusstra\u00dfe in Dreieichenhain verursacht haben. Nach bisherigen Erkenntnissen suchten die Unbekannten im Inneren insgesamt ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>12. Flaschenwurf f\u00fchrte zu Ohrfeige: Zeugensuche der Polizei - Langen<\/b>   (me) Etwa 40 Jahre alt, circa 1,85 Meter gro\u00df, schlank, schwarzes Basecap, Sonnenbrille, graues T-Shirt, schwarze sowie kurze Hose, blauer Rucksack, Mountainbike: Ein Radler mit dieser Personenbeschreibung soll am Sonntag, gegen 19.45 Uhr, einen 18-J\u00e4hrigen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>13. BMW beim Vorbeifahren gestreift - Langen<\/b>   (me) Etwa 5.000 Euro Sachschaden entstand am vergangenen Wochenende an einem BMW mit OF-Kennzeichenschildern. Die Ordnungsh\u00fcter aus Langen ermitteln nun wegen des Verdachts der Verkehrsunfallflucht und suchen in diesem Zusammenhang nach Zeugen. Der Unfall ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>14. Goldschmuck bei Einbruch geklaut: Wer hat etwas gesehen? - Seligenstadt<\/b>   (me) Hochwertigen Goldschmuck erbeutete ein Unbekannter bei einem Einbruch in eine Wohnung in der Berliner Stra\u00dfe (30er-Hausnummern). Zwischen Samstag, 14 Uhr und Sonntag, 15 Uhr, drang der Langfinger gewaltsam in die R\u00e4umlichkeiten ein und nahm die Beute ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-07\">07.07.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309754\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"b9f029d6\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/06\/brand-in-offenbacher-altenwohnheim-feuerwehr-rettungsdienst-und-polizei-im-einsatz\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Brand in Offenbacher Altenwohnheim: Feuerwehr, Rettungsdienst und Polizei im Einsatz<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/06\/brand-in-offenbacher-altenwohnheim-feuerwehr-rettungsdienst-und-polizei-im-einsatz\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Eine verletzte Person und etwa 400.000 Euro Sachschaden sind das Resultat eines Brandes in einem Offenbacher Altenwohnheim in der Nacht zum Montag . Um kurz vor Mitternacht wurden die Feuerwehr, der Rettungsdienst und die Polizei &uuml;ber das Feuer in einem Altenwohnheim ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-06\">06.07.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/06\/brand-in-offenbacher-altenwohnheim-feuerwehr-rettungsdienst-und-polizei-im-einsatz\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2bf52f89\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 06.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Nach Rollerdiebstahl: Schnelle Festnahme von zwei Tatverd\u00e4chtigen - Offenbach<\/b>   (me) Verdacht des besonders schweren Falls des Diebstahls, der Sachbesch\u00e4digung und des unbefugten Gebrauchs eines Fahrzeugs: So lauten die Vorw\u00fcrfe gegen zwei Jugendliche im Alter von 15 Jahren, die am fr\u00fchen Montagmorgen einen Roller von Peugeot gestohlen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Jugendlicher mit Reizstoffspr\u00fchger\u00e4t angegangen: Zeugen gesucht! - Offenbach<\/b>   (fg) Ein Jugendlicher wurde bei einem verabredeten Verkaufsgesch\u00e4ft am Freitagnachmittag, gegen 13.20 Uhr, in der Schlo\u00dfstra\u00dfe (50er-Hausnummern) von einem bis dato Unbekannten mit einem Reizstoffspr\u00fchger\u00e4t angegangen. Der etwa 18 Jahre alte T\u00e4ter, der dunkle ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Streitigkeiten uferten aus: Polizei ermittelt wegen des Verdachts der Volkverhetzung und Beleidigung - Offenbach<\/b>   (fg) Mehrere Personen gerieten in der Jahnstra\u00dfe (einstellige und 10er-Hausnummern) am fr\u00fchen Sonntagmorgen in verbale Streitigkeiten. Diese uferten derart aus, dass die Polizei nun gegen einen 27-J\u00e4hrigen wegen des Verdachts der Volksverhetzung ermittelt. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Bei Brand in Altenwohnheim: Feuerwehr, Rettungsdienst und Polizei im Einsatz - Offenbach<\/b>   (me) Eine verletzte Person und etwa 400.000 Euro Sachschaden sind das Resultat eines Brandes in der Nacht zum Montag. Um kurz vor Mitternacht wurden die Feuerwehr, der Rettungsdienst und die Polizei \u00fcber das Feuer in einem Altenwohnheim im L\u00e4mmerspieler Weg ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Kind bei Zusammensto\u00df mit Opel Astra verletzt - Offenbach<\/b>   (me) Am Montag, um kurz vor 12 Uhr, wurde ein zweij\u00e4hriges Kind bei einem Verkehrsunfall verletzt. Nach dem derzeitigen Ermittlungsstand fuhr der Lenker eines Opels auf der Von-Behring-Stra\u00dfe in Richtung Stiftstra\u00dfe. Das Kleinkind sei unvermittelt auf die ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Vermisste wieder da - Offenbach<\/b>   (me) Die seit Dienstag (30. Juni) vermisste 103-J\u00e4hrige konnte wohlbehalten aufgefunden werden. Die Vermisstensuche wird daher zur\u00fcckgenommen. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Pfefferspray ins Gesicht gespr\u00fcht: Zeugensuche! - M\u00fchlheim am Main<\/b>   (fg) Aus bislang unbekannten Gr\u00fcnden wurde einem 22-J\u00e4hrigen am Sonntagabend, gegen 19.30 Uhr, an einem Fahrkartenautomaten am Bahnhof Pfefferspray in dessen Gesicht gespr\u00fcht. Weshalb es dazu kam, ist unbekannt. Eine Personenbeschreibung liegt nicht vor. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>8. Geparkter Van touchiert: Zeugensuche der Polizei - Dietzenbach<\/b>   (me) Zwischen Montag (29. Juni), 8 Uhr und Mittwoch (1. Juli), 12 Uhr, richtete ein noch unbekannter Wagenlenker einen Schaden von circa 2.000 Euro an einem grauen Van an und fuhr hiernach in unbekannte Richtung davon. Mutma\u00dflich rangierte der Verursacher ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>9. Scheibe mit Kanalschachtdeckel eingeworfen: Kripo sucht Zeugen! - Dietzenbach<\/b>   (fg) Mit einem Kanalschachtdeckel schmissen Unbekannte vergangenes Wochenende eine Fensterscheibe eines Einfamilienhauses in der Wiesenstra\u00dfe (einstellige Hausnummern) ein. Anschlie\u00dfend kletterten die T\u00e4ter ins Innere und durchsuchten mehrere R\u00e4ume; ob sie ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>10. Anh\u00e4nger in der Ahornstra\u00dfe besch\u00e4digt: Wer hat etwas beobachtet? - R\u00f6dermark<\/b>   (me) Offenbar beim Einparken stie\u00df ein Autofahrer gegen einen Anh\u00e4nger mit DA-Kennzeichenschildern und besch\u00e4digte diesen im Bereich der Anh\u00e4ngerkupplung. Laut den bisherigen Ermittlungen ereignete sich der Unfall zwischen Mittwoch, (1. Juli), 19 Uhr und ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>11. Zeugensuche nach Unfallflucht in der Dieburger Stra\u00dfe - Langen<\/b>   (fg) Auf rund 8.500 Euro wird der Schaden gesch\u00e4tzt, den ein unbekannter Verkehrsteilnehmer am Samstagmorgen an zwei in der Dieburger Stra\u00dfe abgestellten Autos verursachte. Ohne sich um die Schadensregulierung zu k\u00fcmmern, machte sich der Verursacher davon. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>12. Kind leicht im Gesicht verletzt: Polizei sucht Zeugen - Langen<\/b>   (me) Die Polizei sucht weiterhin nach Zeugen eines Vorfalls, der sich bereits am Dienstag (23. Juni) in einem Verkaufsgesch\u00e4ft in der Liebigstra\u00dfe (einstellige Hausnummern) zugetragen haben soll. Gegen 16 Uhr befand sich ein Vierj\u00e4hriger mit seiner Mutter ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>13. Auseinandersetzung in Shisha-Bar: Polizei sucht Zeugen - Dreieich<\/b>   (fg) In Sprendlingen kam es am Sonntagmorgen, kurz nach 5 Uhr, zu einer Auseinandersetzung zwischen zwei Personengruppen. Die Polizei ermittelt nun wegen gef\u00e4hrlicher K\u00f6rperverletzung und sucht nach Zeugen. Weshalb es zu dem handfesten Streit in der Shisha-Bar ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-06\">06.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/roedermark-aktuell\" title=\"R\u00f6dermark heute aktuell\">R\u00f6dermark<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6309063\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2abb2769\" href=\"https:\/\/www.op-online.de\/offenbach\/50-stellen-ausgebaut-fdp-stadtrat-weiss-nach-16-jahren-abgewaehlt-stadtpolizei-von-12-auf-94381659.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">FDP-Stadtrat Wei\u00df nach 16 Jahren abgew\u00e4hlt: \u201eStadtpolizei von 12 auf 50 Stellen ausgebaut&quot;<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/offenbach\/50-stellen-ausgebaut-fdp-stadtrat-weiss-nach-16-jahren-abgewaehlt-stadtpolizei-von-12-auf-94381659.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/192\/43192432-stadtrat-paul-gerhard-weiss-offenbach-2Wef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Paul-Gerhard Wei&szlig; war 16 Jahre lang Stadtrat in Offenbach. Nach dem Koalitionswechsel zieht er Bilanz &uuml;ber seine Amtszeit.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-04\">04.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/offenbach\/50-stellen-ausgebaut-fdp-stadtrat-weiss-nach-16-jahren-abgewaehlt-stadtpolizei-von-12-auf-94381659.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"04d8935b\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/04\/polizei-ermittelt-wegen-gefaehrlicher-koerperverletzung-in-dietzenbach\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Polizei ermittelt wegen gef\u00e4hrlicher K\u00f6rperverletzung in Dietzenbach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/04\/polizei-ermittelt-wegen-gefaehrlicher-koerperverletzung-in-dietzenbach\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Nach einer Auseinandersetzung auf einem Supermarktparkplatz in der Rathenaustra&szlig;e (30er-Hausnummern) in Dietzenbach am Donnerstagabend , kurz nach 22 Uhr, ermittelt die Polizei wegen gef&auml;hrlicher K&ouml;rperverletzung und sucht nach Zeugen. Nach bisherigen Erkenntnissen ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-04\">04.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/04\/polizei-ermittelt-wegen-gefaehrlicher-koerperverletzung-in-dietzenbach\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"70fefec0\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307994\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: K\u00fcchenbrand l\u00f6st Feuerwehreinsatz in Wohnhaus aus<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307994\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Rodgau Nieder-Roden  (ots)      Heute Morgen kurz nach halb acht meldeten Anwohner der Hainburgstra\u00dfe in Rodgau Nieder-Roden (Hausnummer im Bereich der 20er) einen K\u00fcchenbrand.  Durch das schnelle Eingreifen der Feuerwehr konnte eine Ausweitung des Feuers auf ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-04\">04.07.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307994\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"cd80e372\" href=\"https:\/\/www.op-online.de\/region\/langen\/aktivist-attackiert-behoerdenmitarbeiter-polizei-langen-94381980.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Skurriler Einsatz in Langen: Aktivist attackiert Beh\u00f6rdenmitarbeiter und Polizei \u2013 \u201em\u00f6glicherweise Urin\u201c<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/langen\/aktivist-attackiert-behoerdenmitarbeiter-polizei-langen-94381980.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/42\/655\/42655519-protestcamp-langen-stadtwald-barrikade-aeste-2iCcoeP4dRef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Im Stadtwald Langen hat ein Unbekannter mutma&szlig;lich Urin auf einen Stadtmitarbeiter gespritzt. Die Polizei nahm ihn fest.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-03\">03.07.2026<\/time> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/langen\/aktivist-attackiert-behoerdenmitarbeiter-polizei-langen-94381980.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"d7c58020\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/03\/kollision-im-kreuzungsbereich-polizei-sucht-zeugen-in-obertshausen\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Kollision im Kreuzungsbereich: Polizei sucht Zeugen bei Obertshausen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/03\/kollision-im-kreuzungsbereich-polizei-sucht-zeugen-in-obertshausen\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Zwei Leichtverletzte und ein Schaden von &uuml;ber 10.000 Euro sind das Ergebnis eines Zusammensto&szlig;es zweier Wagen am Donnerstagabend bei Obertshausen. Gegen 22.15 Uhr stie&szlig;en der Lenker eines schwarzen Opel Zafira und der Fahrer eines wei&szlig;en Mercedes-Benz im Kreuzungsbereich ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-03\">03.07.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/03\/kollision-im-kreuzungsbereich-polizei-sucht-zeugen-in-obertshausen\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"7a4adaf7\" href=\"https:\/\/of-news.de\/dietzenbach\/eskalation-auf-dem-parkplatz-vierer-gruppe-verpruegelt-jugendliche-in-dietzenbach-168719\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf of-news.de\" target=\"_blank\">Eskalation auf dem Parkplatz: Vierer-Gruppe verpr\u00fcgelt Jugendliche in Dietzenbach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/of-news.de\/dietzenbach\/eskalation-auf-dem-parkplatz-vierer-gruppe-verpruegelt-jugendliche-in-dietzenbach-168719\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/of-news.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Am Donnerstagabend sind zwei Jugendliche vor einem Einkaufsmarkt in Dietzenbach Opfer einer gewaltsamen Attacke geworden. Eine Gruppe von vier Unbekannten griff die beiden Teenager, von denen einer aus Dietzenbach stammt, kurz nach 22 Uhr auf einem Parkplatz ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-03\">03.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/of-news.de\/dietzenbach\/eskalation-auf-dem-parkplatz-vierer-gruppe-verpruegelt-jugendliche-in-dietzenbach-168719\/\" title=\"Link zum Artikel auf of-news.de\" target=\"_blank\">of-news.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"f828092e\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307591\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 03.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307591\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Container auf Baustellengel\u00e4nde aufgebrochen: Zeugen gesucht! - Offenbach<\/b>   (fg) Unbekannte waren zwischen Mittwoch, 17 Uhr und Donnerstagmorgen, 6.30 Uhr, auf einem Baustellengel\u00e4nde in der Ziegelstra\u00dfe (20er-Hausnummern) zugange und brachen das Vorh\u00e4ngeschloss eines dortigen Containers auf. Anschlie\u00dfend nahmen die Einbrecher mehrere ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307591\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Kollision im Kreuzungsbereich: Polizei sucht Zeugen - Obertshausen<\/b>   (me) Zwei Leichtverletzte und ein Schaden von \u00fcber 10.000 Euro sind das Ergebnis eines Zusammensto\u00dfes zweier Wagen am Donnerstagabend. Gegen 22.15 Uhr stie\u00dfen der Lenker eines schwarzen Opel Zafira und der Fahrer eines wei\u00dfen Mercedes-Benz im Kreuzungsbereich ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307591\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Zeugensuche: Polizei ermittelt wegen gef\u00e4hrlicher K\u00f6rperverletzung - Dietzenbach<\/b>   (fg) Nach einer Auseinandersetzung auf einem Supermarktparkplatz in der Rathenaustra\u00dfe (30er-Hausnummern) am Donnerstagabend, kurz nach 22 Uhr, ermittelt die Polizei wegen gef\u00e4hrlicher K\u00f6rperverletzung und sucht nach Zeugen.  Nach bisherigen Erkenntnissen ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-03\">03.07.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307591\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"33dafe6b\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307903\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Stadt Langen und Polizei im Stadtwald Langen im Einsatz: Ermittlungen wegen des Verdachts der K\u00f6rperverletzung eingeleitet<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307903\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Langen  (ots)      (fg) Polizeibeamte waren am Freitagvormittag im Rahmen der Vollzugshilfe aufgrund einer bestehenden Allgemeinverf\u00fcgung der Stadt Langen im Langener Stadtwald im Einsatz. Hintergrund ist die \u00dcberpr\u00fcfung der Einhaltung der in der Allgemeinverf\u00fcgung ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-03\">03.07.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6307903\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"66429592\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/02\/e-scooter-prallte-gegen-wagen-zeugensuche-der-polizei-in-seligenstadt\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">E-Scooter prallte gegen Wagen: Zeugensuche der Polizei in Seligenstadt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/02\/e-scooter-prallte-gegen-wagen-zeugensuche-der-polizei-in-seligenstadt\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Zwei minderj&auml;hrige Nutzerinnen eines E-Scooters in Seligenstadt verletzten sich am Dienstagnachmittag bei der Kollision mit einem Auto. Gegen 14.50 Uhr sollen die beiden auf einem E-Scooter auf der Flurstra&szlig;e unterwegs gewesen und in der Folge mit einem aus ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-02\">02.07.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/07\/02\/e-scooter-prallte-gegen-wagen-zeugensuche-der-polizei-in-seligenstadt\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"72778f1f\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306552\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Vermisste wieder da<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306552\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Gelnhausen \/ Langenselbold \/ M\u00fchlheim am Main  (ots)      (me) Die vier seit Montag (29. Juni) beziehungsweise Dienstag (16. und 30. Juni) gesuchten 11, 13 sowie 14 und 17 Jahre alten Vermissten aus Langenselbold, Gelnhausen und M\u00fchlheim am Main konnten wohlbehalten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-02\">02.07.2026<\/time> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306552\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"34891d46\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306874\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 02.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306874\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Langfinger lie\u00dfen Motorrad zur\u00fcck: Zeugensuche! - Offenbach<\/b>   (me) Zwei maskierte M\u00e4nner von kr\u00e4ftiger Statur, beide bekleidet mit einem Tanktop, versuchten am fr\u00fchen Donnerstagmorgen, ein wei\u00dfes Motorrad in der Stiftstra\u00dfe (60er-Hausnummern) zu stehlen, mussten dieses im weiteren Verlauf allerdings besch\u00e4digt zur\u00fccklassen. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306874\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Kriminalpolizei ermittelt und sucht nach Jugendlichen - Rodgau<\/b>   (fg) Am fr\u00fchen Donnerstagmorgen, gegen 0.15 Uhr, geriet ein Abluftschlauch einer mobilen Klimaanlage in der Dr.-Weinholz-Stra\u00dfe (20er-Hausnummern) in Dudenhofen in Brand. Die Kriminalpolizei ermittelt nun wegen des Verdachts der Brandstiftung und sucht nach ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306874\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Hakenkreuze und Beleidigungen in Waldboden geritzt - R\u00f6dermark<\/b>   (me) Die Staatsschutzabteilung des Polizeipr\u00e4sidiums S\u00fcdosthessen ermittelt derzeit wegen des Verwendens von Kennzeichen verfassungswidriger Organisationen, nachdem ein Unbekannter auf einem Waldfestplatz in der Stra\u00dfe \"Zur Walstatt\" mehrere Hakenkreuze und ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-02\">02.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/roedermark-aktuell\" title=\"R\u00f6dermark heute aktuell\">R\u00f6dermark<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306874\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2794cc50\" href=\"https:\/\/www.op-online.de\/offenbach\/103-jaehrige-verschwunden-wer-hat-die-seniorin-aus-offenbach-gesehen-94378299.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">103-J\u00e4hrige verschwunden: Wer hat die Seniorin aus Offenbach gesehen?<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/offenbach\/103-jaehrige-verschwunden-wer-hat-die-seniorin-aus-offenbach-gesehen-94378299.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/181\/43181563-wer-kann-hinweise-zu-der-vermissten-aus-offenbach-geben-Jef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   In Offenbach sucht die Polizei eine 103-J&auml;hrige. Die Seniorin k&ouml;nnte sich in einer hilflosen Lage befinden.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-01\">01.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/offenbach\/103-jaehrige-verschwunden-wer-hat-die-seniorin-aus-offenbach-gesehen-94378299.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"113fe57f\" href=\"https:\/\/www.heusenstamm.de\/de\/buerger-und-stadt\/pressecenter\/aktuelle-meldungen\/detail\/item\/9562\/heusenstamm-belebt-freiwilligen-polizeidienst-wieder-bewerben-bis-5-juli-2026\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf heusenstamm.de\" target=\"_blank\">Heusenstamm belebt Freiwilligen Polizeidienst wieder: Bewerben bis 5. Juli 2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.heusenstamm.de\/de\/buerger-und-stadt\/pressecenter\/aktuelle-meldungen\/detail\/item\/9562\/heusenstamm-belebt-freiwilligen-polizeidienst-wieder-bewerben-bis-5-juli-2026\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/heusenstamm.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die Stadt Heusenstamm f&uuml;hrt den Freiwilligen Polizeidienst wieder ein. Die Stadtverordnetenversammlung hatte Ende 2025 beschlossen, das Modell zu revitalisieren und damit die pr&auml;ventive Sicherhe ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-01\">01.07.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.heusenstamm.de\/de\/buerger-und-stadt\/pressecenter\/aktuelle-meldungen\/detail\/item\/9562\/heusenstamm-belebt-freiwilligen-polizeidienst-wieder-bewerben-bis-5-juli-2026\" title=\"Link zum Artikel auf heusenstamm.de\" target=\"_blank\">heusenstamm.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"43ec59f5\" href=\"https:\/\/www.op-online.de\/region\/neu-isenburg\/familie-mit-drei-kindern-aus-neu-isenburg-abgeschoben-94376601.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Familie mit drei Kindern aus Neu-Isenburg abgeschoben<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/neu-isenburg\/familie-mit-drei-kindern-aus-neu-isenburg-abgeschoben-94376601.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/147\/43147086-buergermeister-herbert-hunkel-in-der-fluechtlingsunterkunft-2016-1jef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Am 22. Juni bringt die Polizei eine kurdisch-t&uuml;rkische Familie zum Flughafen. Die Kinder gingen zur Schule, der Vater arbeitete. Die Fl&uuml;chtlingshilfe fordert die Stadt auf, ein Zeichen zu setzen.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-01\">01.07.2026<\/time> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/neu-isenburg\/familie-mit-drei-kindern-aus-neu-isenburg-abgeschoben-94376601.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"5ddecf84\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306096\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 01.07.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306096\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Versuchter Einbruch in Wettb\u00fcro: Auf frischer Tat ertappt - M\u00fchlheim am Main<\/b>   (me) Ein Einbrecherduo wurde beim Versuch, am Mittwochmorgen in ein Wettb\u00fcro in der Offenbacher Stra\u00dfe gewaltsam einzudringen, durch einen Mitarbeiter auf frischer Tat ertappt und musste daraufhin die Flucht ergreifen. Gegen 2.15 Uhr machten sich die beiden ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306096\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Mehrere hundert Euro Sachschaden mit Graffiti angerichtet: Wer hat etwas gesehen? - Rodgau<\/b>   (me) Unbekannte bespr\u00fchten zwischen Montag, 15 Uhr und Dienstag, 17 Uhr, die W\u00e4nde eines Sch\u00fctzenhauses in der Stra\u00dfe \"Am Nehlsee\" mit Graffiti. Insgesamt konnte die Polizei sechs eher unleserliche Schriftz\u00fcge feststellen. Eine Reinigung der W\u00e4nde d\u00fcrfte ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306096\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Streit m\u00fcndete in Einsatz von Pfefferpistole aus: Hinweise erbeten! - Langen<\/b>   (me) Ein 17-J\u00e4hriger und ein 18 Jahre alter Mann wurden in der Nacht zum Mittwoch mit Pfefferpistolen beschossen und hierdurch leicht verletzt. Nach dem derzeitigen Ermittlungsstand gerieten die beiden gegen 22 Uhr mit einer Gruppe, bestehend aus drei Personen, ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306096\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. E-Scooter prallte gegen Wagen: Zeugensuche der Polizei - Seligenstadt<\/b>   (me) Zwei minderj\u00e4hrige Nutzerinnen eines E-Scooters verletzten sich am Dienstagnachmittag bei der Kollision mit einem Auto. Gegen 14.50 Uhr sollen die beiden auf einem E-Scooter auf der Flurstra\u00dfe unterwegs gewesen und in der Folge mit einem aus der Stra\u00dfe ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-01\">01.07.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306096\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"52d6f05d\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306192\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Vermisstensuche nach Antonia Kliacko<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306192\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   (me) Wo ist Antonia Kliacko? Das fragt die Kriminalpolizei aus Offenbach und bittet die Bev\u00f6lkerung um Mithilfe bei der Suche nach der 103 Jahre alten Vermissten.  Die Seniorin wurde letztmalig am Dienstag (30. Juni) gegen 16 Uhr in der Sch\u00e4ferstra\u00dfe gesehen. ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-07-01\">01.07.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6306192\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"cb89d7c7\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 30.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Zeugensuche nach Einbruch in Kellerabteil - Offenbach<\/b>   (fg) Zwischen Sonntagabend, 19 Uhr und Montag, 18 Uhr, waren Unbekannte in einem Kellerabteil eines Mehrfamilienhauses in der Bernardstra\u00dfe (10er-Hausnummern) zugange, brachen zwei Verschl\u00e4ge auf und nahmen einen Lufterfrischer, eine Bohrmaschine und einen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Unbekannter spr\u00fchte Reizstoff und floh in grauem Mercedes: Zeugensuche! - Dietzenbach<\/b>   (fg) Nach einem Vorfall am Freitagvormittag, kurz vor 12 Uhr, in der Landwehrstra\u00dfe (10er-Hausnummern) ermittelt die Polizei wegen gef\u00e4hrlicher K\u00f6rperverletzung und sucht nach Zeugen. Ein b\u00e4rtiger Unbekannter im Alter von etwa 35 Jahren habe aus dem Beifahrerfenster ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Nach Parkvorgang T\u00fcr ge\u00f6ffnet: Radfahrer st\u00fcrzte und verletzte sich leicht - Neu-Isenburg<\/b>   (fg) Nach einem Parkvorgang in der Dornhofstra\u00dfe (10er-Hausnummern) am Montagabend, kurz vor 19 Uhr, \u00f6ffnete ein Gel\u00e4ndewagen-Fahrer seine T\u00fcr, um auszusteigen. Im Zuge des \u00d6ffnens traf die T\u00fcr einen vorbeifahrenden Radler, der st\u00fcrzte und sich leicht verletzte. ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Taschendiebstahl schlug fehl: Zeugensuche der Polizei - Langen<\/b>   (me) Eine circa 30 Jahre alte Frau, die eine schwarze Tasche mit sich f\u00fchrte und ihr etwa gleichaltriger Komplize, der eine Brille und ein markantes Goldarmband trug, hatten es am Montagmittag auf den Geldbeutel einer \u00e4lteren Dame abgesehen, scheiterten jedoch ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Briefkasten offenbar angez\u00fcndet: Zeugensuche! - Mainhausen<\/b>   (fg) Unbekannte haben einen Briefkasten eines Wohnhauses in der Schulstra\u00dfe (20er-Hausnummern) in Zellhausen offenbar mit einem Feuerzeug besch\u00e4digt. Die Sachbesch\u00e4digung wurde der Polizei am Donnerstagmittag (25. Juni), gegen 12 Uhr, gemeldet. Aufgrund l\u00e4ngerer ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-30\">30.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/mainhausen-aktuell\" title=\"Mainhausen heute aktuell\">Mainhausen<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6305178\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"cf2c9a42\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304169\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Verdacht der gef\u00e4hrlichen K\u00f6rperverletzung: 41-j\u00e4hrige Tatverd\u00e4chtige in Untersuchungshaft<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304169\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Egelsbach  (ots)       Gemeinsame Pressemeldung der Staatsanwaltschaft Darmstadt und des Polizeipr\u00e4sidiums S\u00fcdosthessen    (me) Nach einem mutma\u00dflichen Angriff auf ihren Vater am Freitag (26. Juni) befindet sich eine 41-j\u00e4hrige Frau in Untersuchungshaft.   ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-29\">29.06.2026<\/time> &middot; <a href=\"\/news\/egelsbach-aktuell\" title=\"Egelsbach heute aktuell\">Egelsbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304169\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"f2e5ea00\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 29.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. 61-j\u00e4hriger Rollerfahrer zu schnell unterwegs: Bu\u00dfgeld, Punkte und Fahrverbot erwartet - Offenbach<\/b>     (me) Ein Bu\u00dfgeld von 260 Euro, zwei Punkte im Verkehrszentralregister und ein Monat Fahrverbot kommen auf einen 61 Jahre alten Mann zu, nachdem dieser am Freitagabend auf der M\u00fchlheimer Stra\u00dfe zwischen Offenbach und M\u00fchlheim am Main mit deutlich \u00fcberh\u00f6hter ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Verdacht des Diebstahls von T-Shirts und Wasserpistolen: 23-J\u00e4hriger am Tatort festgenommen - Offenbach<\/b>     (me) Er soll am Samstagnachmittag bei einem Diebstahl von Oberbekleidung und Spielzeug aus einem Gesch\u00e4ft in der Senefelderstra\u00dfe (40er-Hausnummern) beteiligt gewesen sein. So die Vorw\u00fcrfe gegen einen 23 Jahre alten Mann, den die Beamten aus Offenbach noch ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Scheinwerfer, Lenkr\u00e4der und weitere Fahrzeugteile entwendet: Polizei ermittelt und bittet um Hinweise - Offenbach<\/b>     (me) Einen Autositz, zwei Lenkr\u00e4der, ein Navigationssystem und mehrere Scheinwerfer: Diese Gegenst\u00e4nde bauten Langfinger k\u00fcrzlich aus drei Wagen in einer Tiefgarage in der Strahlenbergerstra\u00dfe (80er-Hausnummern) aus. Am Freitag, gegen 13.40 Uhr, erhielt ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Radfahrer st\u00fcrzte und kam in Krankenhaus - M\u00fchlheim am Main<\/b>     (fg) M\u00f6glicherweise aufgrund der Hitze verlor ein Radfahrer am Sonntagnachmittag, kurz nach 16 Uhr, die Kontrolle \u00fcber sein Fahrrad und st\u00fcrzte zu Boden. Aufmerksame Spazierg\u00e4nger eilten dem 60-J\u00e4hrigen zu Hilfe und alarmierten den Rettungsdienst. Der aus ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Nach Zusammensto\u00df auf der Bundesstra\u00dfe 486: Polizei sucht weiterhin nach Zeugen - Langen<\/b>     (me) Nachdem es am Montagnachmittag (22. Juni) auf der Bundesstra\u00dfe 486 im Bereich zur Koberst\u00e4dter Stra\u00dfe zu einem Verkehrsunfall gekommen war, suchen die Beamten der Polizeistation Langen weiterhin nach Zeugen. Hinsichtlich des Unfallhergangs ergaben ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Mutma\u00dflicher Dieb vorl\u00e4ufig festgenommen - Dreieich<\/b>     (fg) Polizeibeamte nahmen am Freitagnachmittag in Sprendlingen einen 28 Jahre alten Verd\u00e4chtigen vorl\u00e4ufig fest; er kam nach einer richterlichen Vorf\u00fchrung in eine Justizvollzugsanstalt. Der 28-J\u00e4hrige habe zuvor, gegen 13.20 Uhr, ein in der Ludwigstra\u00dfe ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Unfall verursacht und davongefahren: Polizei sucht nach rotem Skoda - Seligenstadt<\/b>     (fg) Beim Ausfahren aus einer Parkl\u00fccke auf dem Parkplatz eines Schnellrestaurants im Dr.-Hermann-Neubauer-Ring (50er-Hausnummern) kollidierte die Lenkerin eines roten Skodas am fr\u00fchen Sonntagmorgen, gegen 0.25 Uhr, mit einem geparkten BMW. Hierdurch entstand ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>8. Zeugensuche nach Parkrempler - Hainburg<\/b>     (me) Zwanzig Minuten reichten offenbar am Donnerstagnachmittag aus, um einen Schaden von etwa 1.000 Euro an einem Kombi anzurichten. Zwischen 15.20 Uhr und 15.40 Uhr streifte ein noch unbekannter Autofahrer beim Ein- oder Ausparken einen auf der Offenbacher ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-29\">29.06.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304431\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"06513fb5\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304762\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: R\u00fccknahme Vermisstensuche<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304762\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Neu-Isenburg  (ots)      (fg) Der seit Montagnachmittag gesuchte 87-J\u00e4hrige ist wieder da. Die Vermisstenfahndung wird daher zur\u00fcckgenommen. ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-29\">29.06.2026<\/time> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6304762\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"d74fbc5b\" href=\"https:\/\/www.faz.net\/aktuell\/rhein-main\/region-und-hessen\/wenn-die-polizei-den-einlass-zum-strandbad-stoppt-200976200.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf faz.net\" target=\"_blank\">Und dann l\u00e4sst die Polizei keinen mehr rein<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.faz.net\/aktuell\/rhein-main\/region-und-hessen\/wenn-die-polizei-den-einlass-zum-strandbad-stoppt-200976200.html\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/faz.net.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Als die Hitze am gr&ouml;&szlig;ten ist, schlie&szlig;t das Strandbad Rodgau vor 200 Wartenden den Eingang. Nicht, weil drinnen kein Platz mehr da w&auml;re. Die Bademeister m&uuml;ssen zu viele Schlecht-Schwimmer im Auge behalten.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-28\">28.06.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <\/span><a href=\"https:\/\/www.faz.net\/aktuell\/rhein-main\/region-und-hessen\/wenn-die-polizei-den-einlass-zum-strandbad-stoppt-200976200.html\" title=\"Link zum Artikel auf faz.net\" target=\"_blank\">faz.net<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"0b7b0dbe\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303582\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Pedelec-Fahrer nach Alleinunfall schwer verletzt - Zeugen gesucht<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303582\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Heusenstamm  (ots)      Am Samstagabend verletzte sich ein 58-j\u00e4hriger Pedelec-Fahrer aus Heusenstamm bei einem Alleinunfall in der Hohebergstra\u00dfe schwer.  Gegen 22.17 Uhr befuhr der Mann mit seinem Pedelec die Hohebergstra\u00dfe in Richtung S\u00fcden. Nachdem er die ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-28\">28.06.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303582\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"4cf36a8a\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303600\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Pkw \u00fcberschlug sich auf Autobahnzubringer und geriet in Brand - Fahrer leicht verletzt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303600\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Seligenstadt  (ots)      Ein 34 Jahre alter Autofahrer erlitt bei einem Verkehrsunfall in der Nacht zum Sonntag, gegen 1.49 Uhr, leichte Verletzungen, nachdem sich sein Fahrzeug im Bereich des Seligenst\u00e4dter Dreiecks \u00fcberschlagen hatte und anschlie\u00dfend in Brand ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-28\">28.06.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303600\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"016fe510\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/26\/streit-in-offenbach-eskalierte-ermittlungen-wegen-koerperverletzung-eingeleitet\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Streit in Offenbach eskalierte: Ermittlungen wegen K\u00f6rperverletzung eingeleitet<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/26\/streit-in-offenbach-eskalierte-ermittlungen-wegen-koerperverletzung-eingeleitet\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die Beamten des Polizeireviers in Offenbach wurden am Mittwochabend zu einer k&ouml;rperlichen Auseinandersetzung in die Erlenbruchstra&szlig;e (20er-Hausnummern) in Offenbach gerufen. Vor Ort konnten die Gesetzesh&uuml;ter mehrere Personen, darunter einen 58-J&auml;hrigen sowie ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-26\">26.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/26\/streit-in-offenbach-eskalierte-ermittlungen-wegen-koerperverletzung-eingeleitet\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2fe668f8\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 26.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Festnahme eines mutma\u00dflichen Ladendiebs: Verd\u00e4chtiger hatte offenen Haftbefehl - Offenbach<\/b>   (fg) Polizeibeamte nahmen am Donnerstagabend, kurz nach 20 Uhr, einen mutma\u00dflichen Ladendieb in der L\u00f6wenstra\u00dfe (20er-Hausnummern) vorl\u00e4ufig fest und im weiteren Verlauf mit zum Polizeirevier. Nach bisherigen Erkenntnissen soll der 36 Jahre alte Verd\u00e4chtige, ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Kleidungsst\u00fccke aus Garage entwendet: Zeugensuche! - Dietzenbach<\/b>   (fg) Unbekannte \u00fcberstiegen am Donnerstagabend einen Gartenzaun in der Landwehrstra\u00dfe (20er-Hausnummern) und \u00f6ffneten anschlie\u00dfend eine Garagent\u00fcr auf dem Grundst\u00fcck eines dortigen Einfamilienhauses. Aus diesem nahmen die jugendlichen T\u00e4ter im Alter von 15 ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Hoher Sachschaden nach Unfall mit Porsche - Neu-Isenburg<\/b>   (cb) Einen Sachschaden von etwa 50.000 verursachte der Fahrer eines schwarzen Cayennes am Donnerstag, als dieser mehrere geparkte Fahrzeuge besch\u00e4digte. Nach dem derzeitigen Ermittlungsstand beabsichtigte der 85-j\u00e4hrige Porsche-Lenker seinen Wagen ebenfalls ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Wer hat den Corsa angefahren? - Neu-Isenburg<\/b>   (cb) Wer hat den Corsa angefahren und dadurch einen Sachschaden von knapp 2.500 Euro hinterlassen? Das fragen sich die Ermittler der Polizeistation in Neu-Isenburg und suchen nach Zeugen der Verkehrsunfallflucht. Der Fahrzeugeigent\u00fcmer stellte seinen grauen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Ermittlungen wegen exhibitionistischer Handlungen: Polizei sucht T\u00e4ter - Obertshausen<\/b>   (fg) Ein Unbekannter entbl\u00f6\u00dfte sich am Donnerstag, gegen 17.30 Uhr, in Hausen an einem Bach nahe eines Reitvereins in der Birkenwaldstra\u00dfe und hantierte anschlie\u00dfend an seinem Glied herum. Die Kripo ermittelt nun wegen exhibitionistischer Handlungen und sucht ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Fu\u00dfg\u00e4nger nach Kollision mit Smart schwer verletzt: Zeugensuche! - Rodgau<\/b>   (cb) Schwere Verletzungen erlitt ein 44 Jahre alter Fu\u00dfg\u00e4nger am Donnerstagabend nach der Kollision mit einem Smart. Nach dem bisherigen Erkenntnisstand \u00fcberquerte der Rodgauer mit seinem Hund die Ludwigstra\u00dfe (90er-Hausnummern), wobei er von dem schwarzen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>8. 16-J\u00e4hriger soll Pfefferpistole eingesetzt haben: Ermittlungen eingeleitet - Langen<\/b>   (cb) Wegen des Verdachts der gef\u00e4hrlichen K\u00f6rperverletzung ermitteln die Beamten der Kripo derzeit gegen einen 16-J\u00e4hrigen aus Langen. Dieser soll sich am Donnerstag, gegen 20.30 Uhr, in der Stra\u00dfe \"An der Winkelgasse\" mit einem ihm bekannten 38 Jahre alten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-26\">26.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303086\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"297719c3\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303111\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Mercedes AMG landete auf Dach: Fahrer zog sich leichte Verletzungen zu<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303111\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Bundesstra\u00dfe 45 \/ Rodgau  (ots)      (fg) Am Freitagvormittag, kurz vor 12 Uhr, ereignete sich auf der Bundesstra\u00dfe 45 in Fahrtrichtung Ober-Roden im Bereich der Anschlussstelle Nieder-Roden ein Verkehrsunfall, bei dem ein roter Mercedes auf dem Dach landete. ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-26\">26.06.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6303111\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"1872c6a0\" href=\"https:\/\/www.op-online.de\/offenbach\/eskalation-vor-offenbacher-freibad-jugendlicher-schiesst-auf-sicherheitsmann-94368502.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Eskalation vor Offenbacher Freibad: Jugendlicher schie\u00dft auf Mitarbeiter \u2013 Stadt versch\u00e4rft Sicherheitsregeln<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/offenbach\/eskalation-vor-offenbacher-freibad-jugendlicher-schiesst-auf-sicherheitsmann-94368502.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/101\/43101682-vor-dem-waldschwimmbad-rosenhoehe-in-offenbach-verletzte-ein-jugendlicher-einen-sicherheitsmitarbeiter-mit-einer-schusswaffe-symbolbild-zef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Ein Streit vor dem Freibad Rosenh&ouml;he in Offenbach endete mit einem Schuss. Ein Sicherheitsmitarbeiter wurde verletzt und die Polizei sucht den fl&uuml;chtigen T&auml;ter.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-25\">25.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/offenbach\/eskalation-vor-offenbacher-freibad-jugendlicher-schiesst-auf-sicherheitsmann-94368502.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"f4f6da9f\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/25\/zwei-verletzte-bei-vorfall-im-waldschwimmbad-rosenhoehe\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Zwei Verletzte bei Vorfall im Waldschwimmbad Rosenh\u00f6he<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/25\/zwei-verletzte-bei-vorfall-im-waldschwimmbad-rosenhoehe\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Ein 36-j&auml;hriger Sicherheitsmitarbeiter des Waldschwimmbads Rosenh&ouml;he in Offenbach ist am Mittwochabend bei einer Auseinandersetzung verletzt worden, weswegen die Polizei um Hinweise bittet. Nach bisherigen Erkenntnissen war es bereits am Montag zu Streitigkeiten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-25\">25.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/25\/zwei-verletzte-bei-vorfall-im-waldschwimmbad-rosenhoehe\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"6d54ae68\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6302389\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Vermisste ist wieder da<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6302389\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Rodgau  (ots)      (fg) Die seit Donnerstagvormittag gesuchte 85-J\u00e4hrige ist wieder da. Die Vermisstenfahndung wird daher zur\u00fcckgenommen. ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-25\">25.06.2026<\/time> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6302389\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"7f0b8787\" href=\"https:\/\/www.op-online.de\/region\/neu-isenburg\/hunderennen-bei-34-grad-vierbeiner-begutachten-lieber-die-strecke-94367374.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Hunderennen bei 34 Grad: Manche Vierbeiner begutachten lieber die Strecke<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/neu-isenburg\/hunderennen-bei-34-grad-vierbeiner-begutachten-lieber-die-strecke-94367374.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/74\/43074222-hunderennen-beim-sommerfest-des-vereins-fuer-polizei-und-schutzhunde-in-neu-isenburg-1Hef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Beim Sommerfest des Vereins f&uuml;r Polizei- und Schutzhunde in Neu-Isenburg traten Hunde zum Rennen an. Doch einige Teilnehmer hatten eigene Vorstellungen vom Ablauf.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-25\">25.06.2026<\/time> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/neu-isenburg\/hunderennen-bei-34-grad-vierbeiner-begutachten-lieber-die-strecke-94367374.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"9b13a84a\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/24\/maskierter-raeuber-loeste-polizeieinsatz-in-laemmerspiel-aus\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">\u201cMaskierter R\u00e4uber\u201d l\u00f6ste Polizeieinsatz in L\u00e4mmerspiel aus<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/24\/maskierter-raeuber-loeste-polizeieinsatz-in-laemmerspiel-aus\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Mehrere Personen mit Taschenlampen, hektische Bewegungen im Garten und schlie&szlig;lich Lichtschein in einem Wohnhaus: Ein Notruf aus dem M&uuml;hlheimer Stadtteil L&auml;mmerspiel hat in der Nacht zu Mittwoch einen gr&ouml;&szlig;eren Polizeieinsatz ausgel&ouml;st, der sich letztlich als ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-24\">24.06.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/24\/maskierter-raeuber-loeste-polizeieinsatz-in-laemmerspiel-aus\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"9572b1e5\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/24\/unbekannter-in-offenbach-drohte-mit-messer\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Unbekannter in Offenbach drohte mit Messer<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/24\/unbekannter-in-offenbach-drohte-mit-messer\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die Polizei sucht nach einem bislang unbekannten Mann in Offenbach, der wie folgt beschrieben wird: etwa 30 bis 40 Jahre alt, circa 1,70 Meter gro&szlig; und von schlanker Statur. Er hatte eine Glatze sowie einen Drei-Tage-Bart und fiel insbesondere durch seine sehr ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-24\">24.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/24\/unbekannter-in-offenbach-drohte-mit-messer\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"be8ca1fc\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300927\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: \"Maskierter R\u00e4uber\" l\u00f6ste Polizeieinsatz aus<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300927\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   M\u00fchlheim am Main  (ots)      (lei) Mehrere Personen mit Taschenlampen, hektische Bewegungen im Garten und schlie\u00dflich Lichtschein in einem Wohnhaus: Ein Notruf aus dem Stadtteil L\u00e4mmerspiel hat in der Nacht zu Mittwoch einen gr\u00f6\u00dferen Polizeieinsatz ausgel\u00f6st, ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-24\">24.06.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300927\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"ddf507e6\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 24.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Pr\u00e4ventionsveranstaltung in der Jugendverkehrsschule zur Thematik Rikscha- und Zweiradnutzung - Offenbach<\/b>   (fg) Am vergangenen Mittwoch (17. Juni 2026) fand in der Zeit von 14 Uhr und 17 Uhr auf dem Gel\u00e4nde der Jugendverkehrsschule im Leonhard-Ei\u00dfnert-Park eine Pr\u00e4ventionsveranstaltung rund um \"Rikscha, Fahrrad, Pedelec und E-Bike\" statt. Die Ma\u00dfnahme wurde in ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Verdacht der sexuellen Bel\u00e4stigung in Schwimmbad: Ermittlungen gegen 25-J\u00e4hrigen - Dietzenbach<\/b>   (lei) Nach einem Vorfall am Sonntagnachmittag in einem Schwimmbad an der Offenthaler Stra\u00dfe ermittelt die Kriminalpolizei wegen des Verdachts der sexuellen Bel\u00e4stigung gegen einen 25 Jahre alten Mann.  Nach bisherigen Erkenntnissen soll sich der Vorfall gegen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Mutma\u00dflich mit Waffe gedroht: Zeugensuche! - Dietzenbach<\/b>   (fg) In der Justus-von-Liebig-Stra\u00dfe (einstellige Hausnummern) kam es am Dienstagabend zu einer lautstarken Auseinandersetzung. Die Polizei ermittelt nun wegen des Verdachts der Bedrohung und sucht einen etwa 25 Jahre alten, schwarzhaarigen Mann. Der Gesuchte ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Betr\u00fcger brachten Rentnerin um ihr Erspartes: Zeugen gesucht! - M\u00fchlheim am Main<\/b>   (cb) Betr\u00fcger brachten eine Rentnerin am Dienstag um ihr \u00fcber Jahre Erspartes, in der Summe um mehrere zehntausend Euro. Das Telefon der M\u00fchlheimerin klingelte gegen 15 Uhr. Am anderen Ende gab sich eine Frau als Polizeibeamtin aus. Sie tischte der Seniorin ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Streit uferte aus: Ermittlungen wegen gef\u00e4hrlicher K\u00f6rperverletzung - Rodgau<\/b>   (fg) In Weiskirchen uferte ein Streit am Dienstagabend, kurz nach 21 Uhr, in der Schillerstra\u00dfe im Bereich einer dortigen Bushaltestelle in eine handfeste Auseinandersetzung aus. Gegen einen 36-J\u00e4hrigen wird nun wegen des Verdachts der gef\u00e4hrlichen K\u00f6rperverletzung ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Pr\u00e4ventionsabend in R\u00f6dermark: Schutz vor Anfeindungen und digitalen Gefahren im Fokus - R\u00f6dermark<\/b>   (cb) Beleidigungen, Bedrohungen und pers\u00f6nliche Angriffe auf Personen des \u00f6ffentlichen Lebens nehmen bundesweit sp\u00fcrbar zu. L\u00e4ngst sind davon nicht mehr nur Politikerinnen und Politiker auf Landes- oder Bundesebene betroffen, sondern auch kommunale Amts- ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-24\">24.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/roedermark-aktuell\" title=\"R\u00f6dermark heute aktuell\">R\u00f6dermark<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6301235\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"8cc59dbc\" href=\"https:\/\/www.op-online.de\/region\/heusenstamm\/autofahrerin-geraet-in-den-gegenverkehr-sie-stirbt-an-ihren-verletzungen-94365689.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Autofahrerin ger\u00e4t in den Gegenverkehr \u2013 sie stirbt an ihren Verletzungen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/heusenstamm\/autofahrerin-geraet-in-den-gegenverkehr-sie-stirbt-an-ihren-verletzungen-94365689.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/79\/43079539-der-unfallort-auf-der-bruecke-ueber-der-a3-zwischen-heusenstamm-und-offenbach-zef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Auf der Dietzenbacher Stra&szlig;e stirbt eine Suzuki-Fahrerin nach einem Frontalzusammensto&szlig;. Die Polizei sucht Zeugen.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-23\">23.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/heusenstamm\/autofahrerin-geraet-in-den-gegenverkehr-sie-stirbt-an-ihren-verletzungen-94365689.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"afd8c49d\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 23.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Zivile Kontrollen f\u00fchrten zur vorl\u00e4ufigen Festnahme eines mutma\u00dflichen Unfallverursachers - Stadt Offenbach und Landkreis Offenbach<\/b>   (cb) Bei gezielt durchgef\u00fchrten, zivilen Kontrollma\u00dfnahmen am Montagabend konnten Beamte der Polizeistation Heusenstamm den mutma\u00dflichen Fahrer einer Verkehrsunfallflucht (wir berichteten unter:  https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568 ) vom ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Zeugensuche: Hausfassade nach Flaschenwurf besch\u00e4digt - Offenbach<\/b>   (fg) Unbekannte warfen am Dienstagmorgen, gegen 2.20 Uhr, in der Bismarckstra\u00dfe im Bereich der 70er-Hausnummern eine Glasflasche mit einer mutma\u00dflich brennbaren Fl\u00fcssigkeit gegen eine dortige Hausfassade. M\u00f6glicherweise beabsichtigten die T\u00e4ter, die mit einem ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Unbekannter drohte mit Messer: Polizei sucht mit Personenbeschreibung - Offenbach<\/b>   (fg) Die Polizei sucht nach einem bislang unbekannten Mann, der wie folgt beschrieben wird: etwa 30 bis 40 Jahre alt, circa 1,70 Meter gro\u00df und von schlanker Statur. Er hatte eine Glatze sowie einen Drei-Tage-Bart und fiel insbesondere durch seine sehr schlechten ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Aufmerksamer Unfallzeuge: Fahrer unter Alkoholeinfluss unterwegs - Rodgau<\/b>   (fg) Ein aufmerksamer Zeuge meldete sich am Freitagmorgen, gegen 5.30 Uhr, bei der Polizei und gab an, einen Unfall im Bereich des Tannenm\u00fchlkreisels beobachtet zu haben. Eine herbeigeeilte Streife machte den Unfallwagen kurz darauf ausfindig und kontrollierte ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Falsche Handwerker waren unterwegs: Hinweise erbeten - Langen<\/b>   (cb) Falsche Handwerker waren am Montagvormittag im Forstring unterwegs und erbeuteten aus der Wohnung einer Seniorin die Geldb\u00f6rse. Zuvor gelangten sie in den Hausflur des Mehrparteienhauses, begaben sich zur Wohnung der Rentnerin und klingelten. Als die ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-23\">23.06.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300295\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"b0021219\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300502\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 23.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300502\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>Berufsverkehr: eine Person verletzt - Offenbach<\/b>  Zu einem Auffahrunfall, bei dem ein Peugeot sowie ein Skoda involviert waren, kam es am Dienstagmorgen auf der M\u00fchlheimer Stra\u00dfe im Bereich der 210er-Hausnummern. Der 33 Jahre alter Fahrer eines wei\u00dfen Opels fuhr gegen 7.30 Uhr dem vor ihm befindlichen wei\u00dfen ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-23\">23.06.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300502\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"b9647e4b\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300657\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Unbekannter soll M\u00e4dchen ber\u00fchrt haben: Polizei ermittelt und sucht Zeugen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300657\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Neu-Isenburg  (ots)      (lei) Nach einer Begegnung zwischen einer Zehnj\u00e4hrigen und einem Unbekannten am Dienstagmittag hat die Polizei Ermittlungen wegen des Verdachts des sexuellen Missbrauchs von Kindern aufgenommen.  Nach ersten Erkenntnissen der Beamten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-23\">23.06.2026<\/time> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6300657\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"25217fec\" href=\"https:\/\/www.op-online.de\/region\/dietzenbach\/dietzenbach-roller-fahrer-wirft-steine-gegen-auto-94362805.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Jugendlicher wirft Steine gegen Auto \u2013 er war in einer Gruppe auf E-Scooter unterwegs<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/dietzenbach\/dietzenbach-roller-fahrer-wirft-steine-gegen-auto-94362805.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/43\/56\/43056000-ein-blaulicht-ist-auf-dem-dach-eines-polizeifahrzeugs-zu-sehen-2uQH6He42Mef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Unbekannte Jugendliche sollen in Dietzenbach Steine auf ein Auto geworfen haben. Die Polizei ermittelt wegen des Verdachts auf gef&auml;hrlichen Eingriff in den Stra&szlig;enverkehr.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-22\">22.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/dietzenbach\/dietzenbach-roller-fahrer-wirft-steine-gegen-auto-94362805.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"84d45e39\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/22\/bewaffneter-raubueberfall-auf-spargelstand-in-heusenstamm\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Bewaffneter Raub\u00fcberfall auf Spargelstand in Heusenstamm<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/22\/bewaffneter-raubueberfall-auf-spargelstand-in-heusenstamm\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Zwei bislang unbekannte M&auml;nner haben am Sonntagnachmittag einen Spargelverkaufsstand in der Ringstra&szlig;e in Heusenstamm &uuml;berfallen und dabei Bargeld sowie weitere Gegenst&auml;nde erbeutet. Die Polizei hat die Ermittlungen aufgenommen und sucht nun nach Zeugen. Nach ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-22\">22.06.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/22\/bewaffneter-raubueberfall-auf-spargelstand-in-heusenstamm\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"3668c1b2\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299044\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Ermittlungen gegen 62-J\u00e4hrigen wegen Verdachts der gef\u00e4hrlichen K\u00f6rperverletzung<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299044\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   (lei) Wegen des Verdachts der gef\u00e4hrlichen K\u00f6rperverletzung muss sich seit Freitagmorgen ein 62-J\u00e4hriger verantworten. Er soll demnach einen 60-J\u00e4hrigen vor einem Mehrfamilienhaus in der M\u00fchlheimer Stra\u00dfe (220er-Hausnummern) mit einem l\u00e4nglichen Gegenstand ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-22\">22.06.2026<\/time> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299044\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2fd0e540\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 22.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Z\u00fcgige Festnahme: 40-J\u00e4hriger soll sich entbl\u00f6\u00dft und angefasst haben - Offenbach<\/b>     (fg) Dank einer aufmerksamen Zeugin nahm eine Streifenbesatzung am Freitagmorgen, kurz vor 8 Uhr, einen 40-J\u00e4hrigen vorl\u00e4ufig fest. Dieser soll sich zuvor in der Gerberstra\u00dfe im Bereich der einstelligen Hausnummern entbl\u00f6\u00dft, sein Glied herausgeholt und ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Bargeld und Schmuck von Einbrechern mitgenommen - Offenbach<\/b>     (cb) Mit Bargeld und Schmuck im Wert von \u00fcber 10.000 Euro fl\u00fcchteten Langfinger, nachdem diese am Freitag in eine Wohnung in der Kaiserstra\u00dfe (110er-Hausnummern) eingebrochen waren. Die T\u00e4ter verschafften sich unbemerkt Zutritt in den Hausflur des Mehrfamilienhauses ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Mehrere Kellerabteile aufgebrochen: Zeugen bitte melden! - Offenbach<\/b>     (cb) Unbekannte gelangten zwischen Freitag, 9 Uhr und Samstag, 12.30 Uhr, in ein Mehrfamilienhaus in der Konrad-Adenauer-Stra\u00dfe (60er-Hausnummern) und brachen anschlie\u00dfend mehrere Kellerabteile auf. Jedes der bisher gemeldeten 16 Abteile wurde durch die ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Zeugensuche nach Unfallflucht: Fahrzeug besch\u00e4digte Bushaltestelle - Obertshausen<\/b>     (cb) Die Beamten der Polizeistation in Heusenstamm suchen Zeugen einer Verkehrsunfallflucht, die sich am Sonntag in der Bahnhofstra\u00dfe (30er-Hausnummern) ereignete. Nach dem derzeitigen Stand der Ermittlungen fuhr der bislang unbekannte Unfallverursacher ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Schmuck und Bargeld aus Einfamilienhaus gestohlen: Zeugen gesucht! - Obertshausen<\/b>     (fg) Unbekannte sind am Samstag zwischen 11.30 Uhr und 17 Uhr in ein Einfamilienhaus in der B\u00f6hmerwaldstra\u00dfe (10er-Hausnummern) eingedrungen und nahmen Schmuck sowie Bargeld mit. Nach bisherigen Erkenntnissen hebelten die Einbrecher eine Kellert\u00fcr auf, ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Mutma\u00dflich unter Drogeneinfluss: Verd\u00e4chtiger kam mit Rettungswagen in Klinik - M\u00fchlheim am Main<\/b>     (fg) Wegen des Verdachts exhibitionistischer Handlungen ermittelt die Polizei gegen einen 18 Jahre alten Verd\u00e4chtigen, der sich am Freitagabend in der Schlesierstra\u00dfe in L\u00e4mmerspiel mutma\u00dflich unter dem Einfluss von Rauschmitteln entbl\u00f6\u00dft und angefasst ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Geschlagen, getreten und Telefon geraubt: Zeugensuche! - Langen<\/b>     (fg) Mehrere Unbekannte gingen einen 21-J\u00e4hrigen am fr\u00fchen Montagmorgen, gegen 1.20 Uhr, gemeinschaftlich an und raubten letztlich dessen Mobiltelefon. Nach bisherigen Erkenntnissen liefen die 13 bis 15 Jahre alten T\u00e4ter dem 21-J\u00e4hrigen vom Bahnhof Langen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>8. Unbekannte machten sich an Kiosk zu schaffen: Zeugen gesucht! - Langen<\/b>     (cb) Unbekannte beabsichtigten offenbar in einen Kiosk im Freibad in der Teichstra\u00dfe (20er-Hausnummern) einzudringen. Hierzu schoben sie zwischen Freitag, 22.30 Uhr und Samstag, 7.50 Uhr, den Rollladen des Verkaufsladens nach oben und versuchten gewaltsam ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>9. Einbrecher stiegen \u00fcber K\u00fcchenfenster ein - Egelsbach<\/b>     (cb) Am Freitag verschafften sich Einbrecher \u00fcber ein zerst\u00f6rtes K\u00fcchenfenster Zutritt in ein Einfamilienhaus in der Ostendstra\u00dfe (40er-Hausnummern). Anschlie\u00dfend durchsuchten sie s\u00e4mtliche R\u00e4umlichkeiten nach Wertgegenst\u00e4nden. Ob sie bei der Tat, die sich ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>10. Jugendliche sollen Autos besch\u00e4digt haben: Ermittlungen eingeleitet - Hainburg<\/b>     (cb) Mitteiler informierten am Sonntag die Beamten in Seligenstadt \u00fcber zwei Jugendliche, welche mehrere Fahrzeuge in der Spessartstra\u00dfe (10er-Hausnummern) besch\u00e4digt haben sollen. Im Zuge der sofort eingeleiteten Fahndungsma\u00dfnahmen konnten zwei Teenager ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>11. Unfallflucht auf Autobahn: Verkehrsteilnehmer machte sich nach abruptem Spurwechsel davon - Autobahn 3 \/ Mainhausen<\/b>     (fg) Am Freitagnachmittag ereignete sich auf der Autobahn 3 in H\u00f6he des Seligenst\u00e4dter Dreiecks in Richtung W\u00fcrzburg eine Verkehrsunfallflucht, weshalb die Polizei ermittelt und nach Zeugen sucht. Ein unbekannter Verkehrsteilnehmer habe einen pl\u00f6tzlichen ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>12. Mercedes angedotzt: Hinweise erbeten - Mainhausen<\/b>     (cb) Ein Mercedes, welcher am Fahrbahnrand der Stra\u00dfe \"Wingertspfad\" (10er-Hausnummern) abgestellt war, weist seit Samstag Besch\u00e4digungen in H\u00f6he von etwa 1.200 Euro an der Fahrzeugfront auf. Der Fahrzeugeigent\u00fcmer parkte seinen Mercedes C180 am Freitag, ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-22\">22.06.2026<\/time> &middot; <a href=\"\/news\/egelsbach-aktuell\" title=\"Egelsbach heute aktuell\">Egelsbach<\/a> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/mainhausen-aktuell\" title=\"Mainhausen heute aktuell\">Mainhausen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6299568\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"5894577b\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/20\/mai-einsaetze-der-stadtpolizei-offenbach-laermende-gaeste-hilferufe-aus-einem-hotel-und-koerperverletzung\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Mai-Eins\u00e4tze der Stadtpolizei Offenbach: L\u00e4rmende G\u00e4ste, Hilferufe aus einem Hotel und K\u00f6rperverletzung<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/20\/mai-einsaetze-der-stadtpolizei-offenbach-laermende-gaeste-hilferufe-aus-einem-hotel-und-koerperverletzung\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Das gute Wetter bescherte der Stadtpolizei viele Ruhest&ouml;rungen. Darunter eine Familie, die durch ihren L&auml;rm andere Hotelg&auml;ste vergrault hatte. Gefordert war sie auch bei vielen anderen Eins&auml;tzen: Ein Junge wurde von einem Jugendlichen bedroht und getreten, ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-20\">20.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/20\/mai-einsaetze-der-stadtpolizei-offenbach-laermende-gaeste-hilferufe-aus-einem-hotel-und-koerperverletzung\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"9cdb48ed\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/zwei-braende-innerhalb-weniger-minuten-in-offenbach\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Kripo pr\u00fcft Zusammenhang: Zwei Br\u00e4nde innerhalb weniger Minuten in Offenbach<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/zwei-braende-innerhalb-weniger-minuten-in-offenbach\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Zwei Br&auml;nde in unmittelbarer r&auml;umlicher und zeitlicher N&auml;he haben in der Nacht zu Freitag Feuerwehr und Polizei in Offenbach besch&auml;ftigt. Nun ermittelt die Kriminalpolizei und geht dabei dem Verdacht nach, dass die Vorf&auml;lle miteinander in Zusammenhang stehen ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-19\">19.06.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/zwei-braende-innerhalb-weniger-minuten-in-offenbach\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"3dd59b8a\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/seligenstaedter-dreieck-offenbach-zahlreiche-verstoesse-bei-fahrzeug-und-personenkontrollen-festgestellt\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Seligenst\u00e4dter Dreieck\/Offenbach: Zahlreiche Verst\u00f6\u00dfe bei Fahrzeug- und Personenkontrollen festgestellt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/seligenstaedter-dreieck-offenbach-zahlreiche-verstoesse-bei-fahrzeug-und-personenkontrollen-festgestellt\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Im Rahmen der gerade stattfindenden, europaweiten ROADPOL-Aktionswoche &quot;Alcohol &#38; Drugs&quot; f&uuml;hrten Verkehrsspezialisten des Polizeipr&auml;sidiums S&uuml;dosthessen am Donnerstag zwischen 16 Uhr und Mitternacht umfangreiche Fahrzeug- und Personenkontrollen am Autobahndreieck ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-19\">19.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/seligenstaedter-dreieck-offenbach-zahlreiche-verstoesse-bei-fahrzeug-und-personenkontrollen-festgestellt\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"2d0d317d\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/kontrollen-im-rahmen-der-innenstadtoffensive-mehrere-verstoesse-in-offenbach-festgestellt\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Kontrollen im Rahmen der Innenstadtoffensive: Mehrere Verst\u00f6\u00dfe in Offenbach festgestellt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/kontrollen-im-rahmen-der-innenstadtoffensive-mehrere-verstoesse-in-offenbach-festgestellt\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Mit gezielten Kontrollen im Innenstadtbereich setzte die Polizei in Offenbach am Mittwoch ihre Ma&szlig;nahmen zur St&auml;rkung der Sicherheit und Ordnung im &ouml;ffentlichen Raum fort. Unter anderem mit Unterst&uuml;tzung von Kr&auml;ften des Hessischen Polizeipr&auml;sidiums Einsatz ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-19\">19.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/19\/kontrollen-im-rahmen-der-innenstadtoffensive-mehrere-verstoesse-in-offenbach-festgestellt\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"67ab6739\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297921\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Zwei Br\u00e4nde innerhalb weniger Minuten: Kriminalpolizei pr\u00fcft Zusammenhang<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297921\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   (lei) Zwei Br\u00e4nde in unmittelbarer r\u00e4umlicher und zeitlicher N\u00e4he haben in der Nacht zu Freitag Feuerwehr und Polizei in Offenbach besch\u00e4ftigt. Nun ermittelt die Kriminalpolizei und geht dabei dem Verdacht nach, dass die Vorf\u00e4lle miteinander in Zusammenhang ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-19\">19.06.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297921\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"27807328\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/18\/fuenf-leichtverletzte-bei-unfall-mit-vier-beteiligten-fahrzeugen-am-tannenmuehlkreisel-bei-obertshausen\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">F\u00fcnf Leichtverletzte bei Unfall mit vier beteiligten Fahrzeugen am Tannenm\u00fchlkreisel bei Obertshausen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/18\/fuenf-leichtverletzte-bei-unfall-mit-vier-beteiligten-fahrzeugen-am-tannenmuehlkreisel-bei-obertshausen\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Folgenreich verlief ein Moment mutma&szlig;licher Unaufmerksamkeit am Dienstag im Bereich des Tannenm&uuml;hlkreisels bei Obertshausen. F&uuml;nf Personen sind dort bei einem Verkehrsunfall am Nachmittag leicht verletzt worden. Dessen genauen Hergang arbeitet nun die Polizei ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-18\">18.06.2026<\/time> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/18\/fuenf-leichtverletzte-bei-unfall-mit-vier-beteiligten-fahrzeugen-am-tannenmuehlkreisel-bei-obertshausen\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"64b89408\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 18.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Kontrollen im Rahmen der Innenstadtoffensive: Mehrere Verst\u00f6\u00dfe festgestellt - Offenbach<\/b>   (lei) Mit gezielten Kontrollen im Innenstadtbereich setzte die Polizei in Offenbach am Mittwoch ihre Ma\u00dfnahmen zur St\u00e4rkung der Sicherheit und Ordnung im \u00f6ffentlichen Raum fort. Unter anderem mit Unterst\u00fctzung von Kr\u00e4ften des Hessischen Polizeipr\u00e4sidiums ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Laptop von Einbrechern mitgenommen - Offenbach<\/b>   (cb) Einbrecher, die am Mittwoch in eine Wohnung in der Senefelderstra\u00dfe (70er-Hausnummern) eingebrochen waren, fl\u00fcchteten nach bisherigen Kenntnissen mit einem Laptop. Zuvor verschafften sie sich Zutritt in das Mehrfamilienhaus, begaben sich zur Wohnung ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Neu errichtete L\u00e4rmschutzwand bespr\u00fcht: Zeugen gesucht! - Neu-Isenburg<\/b>   (cb) Einen Sachschaden von sch\u00e4tzungsweise 2.500 Euro verursachten bislang Unbekannte, als diese eine neu errichtete L\u00e4rmschutzwand und noch nicht verbaute Einzelelemente in der Bahnhofstra\u00dfe mit verschiedenen Schriftz\u00fcgen und Symbolen beschmierten. Laut ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. F\u00fcnf Leichtverletzte bei Unfall mit vier beteiligten Fahrzeugen - Obertshausen<\/b>   (lei) Folgenreich verlief ein Moment mutma\u00dflicher Unaufmerksamkeit am Dienstag im Bereich des Tannenm\u00fchlkreisels. F\u00fcnf Personen sind dort bei einem Verkehrsunfall am Nachmittag leicht verletzt worden. Dessen genauen Hergang arbeitet nun die Polizei in Heusenstamm ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Motorrad aus Innenhof geklaut: Zeugen bitte melden! - Hainburg<\/b>   (cb) Motorraddiebe hatten es auf eine Maschine abgesehen, die im Innenhof eines Mehrfamilienhauses in der Auheimer Stra\u00dfe (10er-Hausnummern) abgestellt war. Das Motorrad mit OF-Kennzeichen stellte der Eigent\u00fcmer am Dienstag, gegen 18 Uhr, ab. Als er am n\u00e4chsten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-18\">18.06.2026<\/time> &middot; <a href=\"\/news\/hainburg-aktuell\" title=\"Hainburg heute aktuell\">Hainburg<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6297064\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"6989fdda\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/17\/vollbremsung-an-zebrastreifen-in-offenbach-radfahrerin-stuerzte\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Vollbremsung an Zebrastreifen in Offenbach: Radfahrerin st\u00fcrzte<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/17\/vollbremsung-an-zebrastreifen-in-offenbach-radfahrerin-stuerzte\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Die Polizei waren am Montagabend bei einem Verkehrsunfallgeschehen im Isenburgring in Offenbach eingesetzt, nachdem es dort zu einer leichten Kollision zwischen einem Auto und einer jungen Radfahrerin gekommen war. Laut bisherigen Informationen der Beamten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-17\">17.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/17\/vollbremsung-an-zebrastreifen-in-offenbach-radfahrerin-stuerzte\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"6a191322\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6296422\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 17.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6296422\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Mutma\u00dfliche Unfallflucht am Wetterpark: Jugendliche sollen danach auch eine Pfefferpistole eingesetzt haben - Offenbach<\/b>   (lei) Aus n\u00e4chster N\u00e4he und aus einer Gruppe heraus soll ein Jugendlicher am Dienstagabend am Wetterpark mit einer sogenannten Pfefferpistole auf einen 59-J\u00e4hrigen geschossen und diesen dabei verletzt haben. Der Mann kam mit Blessuren im Gesicht zur weiteren ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6296422\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Wer hat den Zettel am gr\u00fcnen Opel hinterlassen? - Dreieich<\/b>   (cb) Ein bis dato unbekannter Zeuge hat am Dienstagnachmittag an einem besch\u00e4digten Opel eine Nachricht mit dem Hinweis auf einen Unfall hinterlassen, weshalb die Beamten in Neu-Isenburg nun diesen und weitere Unfallzeugen suchen. Nach dem derzeitigen Stand ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6296422\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Abgestellte Kabeltrommel mitgenommen: Polizei bittet um Hinweise - Heusenstamm<\/b>   (cb) Zwei Mitarbeiter eines Energieunternehmens waren am Dienstagvormittag im Bereich der Frankfurter Stra\u00dfe (einstellige Hausnummern) eingesetzt, als bislang Unbekannte eine Kabeltrommel klauten. Diese wurde zwischen 8.45 Uhr und 9.30 Uhr durch die Mitarbeiter ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6296422\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Unbekannte fl\u00fcchteten mit erbeuteter Tasche und Handy - R\u00f6dermark<\/b>   (cb) Seine Tasche sowie sein Handy nahmen zwei bislang Unbekannte am Mittwoch einem 20-J\u00e4hrigen ab und fl\u00fcchteten mit ihrer Beute. Nach bisherigem Ermittlungsstand sprach das Duo den jungen Mann, welcher auf einer Bank in der Dieburger Stra\u00dfe (30er-Hausnummern) ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-17\">17.06.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/roedermark-aktuell\" title=\"R\u00f6dermark heute aktuell\">R\u00f6dermark<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6296422\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"dfa06d23\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294971\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Ermittlungen gegen 19-J\u00e4hrigen wegen Verdacht des Raubes<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294971\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Langen  (ots)      (lei) Nach einem Vorfall am Montagabend in der Teichstra\u00dfe hat die Polizei Ermittlungen wegen des Verdachts des Raubes aufgenommen. Im Fokus steht dabei ein 19-J\u00e4hriger, der einer 18-J\u00e4hrigen im Bereich des Freibades gewaltsam deren Handtasche ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-16\">16.06.2026<\/time> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294971\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"d306ab2a\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295074\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Jugendlicher mit Pfefferspray verletzt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295074\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Neu-Isenburg  (ots)      (lei) Aufgaben unter der Gewaltandrohung l\u00f6sen zu m\u00fcssen - mit dieser Situation sahen sich am Montagabend zwei Jugendliche im Bereich eines Fast-Food-Restaurants in der Carl-Friedrich-Gau\u00df-Stra\u00dfe konfrontiert.  Zwei bislang Unbekannte ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-16\">16.06.2026<\/time> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295074\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"916feee8\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 16.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Vollbremsung an Zebrastreifen: Radfahrerin st\u00fcrzte - Offenbach<\/b>   (lei) Die Polizei waren am Montagabend bei einem Verkehrsunfallgeschehen im Isenburgring eingesetzt, nachdem es dort zu einer leichten Kollision zwischen einem Auto und einer jungen Radfahrerin gekommen war. Laut bisherigen Informationen der Beamten wollte ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Unbekannter beleidigte junge Frau: Hinweise erbeten - Dietzenbach<\/b>   (cb) Ein etwa 50 Jahre alter Mann mit l\u00e4ngeren dunkelblonden Haaren, der ein gr\u00fcn gemustertes Hemd trug, beleidigte am Montagabend eine junge Frau. Sie war gegen 22.50 Uhr im Dr.-Heumann-Weg (einstellige Hausnummern) unterwegs, als ihr der Unbekannte mehrere ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Kind bei Unfall mit E-Scooter verletzt - Obertshausen<\/b>   (lei) Ein Achtj\u00e4hriger ist am Montagnachmittag bei einem Unfall in der Beethovenstra\u00dfe mit einem E-Scooter gest\u00fcrzt und hat sich dabei noch unklare Verletzungen zugezogen. Der Junge war dort gegen 17.10 Uhr mit dem kleinen Gef\u00e4hrt im Bereich der Robert-Schumann-Stra\u00dfe ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Jugendliche bei Zusammensto\u00df mit an Kreuzung leicht verletzt - Dreieich<\/b>   (lei) Bei einem Zusammensto\u00df zwischen einem Auto und einem Fahrrad ist am Montagabend eine 17-J\u00e4hrige leicht verletzt worden. Nach ersten Erkenntnissen war die Jugendliche gegen 23 Uhr mit ihrem wohl unbeleuchteten Rad auf der Hauptstra\u00dfe in s\u00fcdliche Richtung ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Zwei Personen verletzt: Ermittlungen aufgenommen - Dreieich<\/b>   (cb) Zwei Personen erlitten bei einer Auseinandersetzung am Sonntag, gegen 4.55 Uhr, leichte Verletzungen, weshalb die Kriminalpolizei die Ermittlungen aufgenommen hat. Nach dem derzeitigen Stand der Ermittlungen begegneten sich ein 30-j\u00e4hriger Mann, ein ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>6. Mutma\u00dfliche Baustellendiebe festgenommen - Langen<\/b>   (cb) Ein Mitteiler informierte die Polizei am fr\u00fchen Dienstagmorgen, dass er gerade zwei M\u00e4nner dabei beobachtete, wie diese mehrere D\u00e4mmplatten von einer Baustelle in ihren eigens mitgebrachten Anh\u00e4nger verladen w\u00fcrden. In der Folge konnten die entsandten ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>7. Audi im Vorbeifahren gestreift: Zeugen bitte melden! - Mainhausen<\/b>   (cb) Ein Audi Q2, welcher am Fahrbahnrand der Humboldtstra\u00dfe (10er-Hausnummern) abgeparkt war, weist seit Montag einen Schaden in H\u00f6he von knapp 4.000 Euro auf. Der Fahrzeugeigent\u00fcmer stellte seinen wei\u00dfen Wagen gegen 15.45 Uhr ab und musste nur 30 Minuten ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-16\">16.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/mainhausen-aktuell\" title=\"Mainhausen heute aktuell\">Mainhausen<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/obertshausen-aktuell\" title=\"Obertshausen heute aktuell\">Obertshausen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/seligenstadt-aktuell\" title=\"Seligenstadt heute aktuell\">Seligenstadt<\/a> &middot; <a href=\"\/news\/unfaelle-offenbach-am-main\" title=\"Unf\u00e4lle Offenbach am Main\">Unfall<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6295508\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"43c8635f\" href=\"https:\/\/www.op-online.de\/region\/egelsbach\/steinwurf-auf-a661-polizei-fahndet-nach-jugendlichen-taetern-94352191.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Steinwurf auf Autobahn im Kreis Offenbach: Polizei sucht nach Zeugen<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/region\/egelsbach\/steinwurf-auf-a661-polizei-fahndet-nach-jugendlichen-taetern-94352191.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/42\/962\/42962465-polizei-zieht-reisebus-aus-den-verkehr-1Qef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Nach einem Steinwurf auf ein fahrendes Auto in Egelsbach fahndet die Polizei nach den mutma&szlig;lichen jugendlichen T&auml;tern. Hinweise sind erw&uuml;nscht.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-16\">16.06.2026<\/time> &middot; <a href=\"\/news\/egelsbach-aktuell\" title=\"Egelsbach heute aktuell\">Egelsbach<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/region\/egelsbach\/steinwurf-auf-a661-polizei-fahndet-nach-jugendlichen-taetern-94352191.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"4de72e07\" href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/15\/feuer-in-leerstehendem-haus-in-roedermark\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">Feuer in leerstehendem Haus in R\u00f6dermark<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/15\/feuer-in-leerstehendem-haus-in-roedermark\/\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/rheinmainverlag.de.png\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Ein Brand in einem seit l&auml;ngerer Zeit leerstehendem Haus hat am Sonntagabend bei R&ouml;dermark-Waldacker einen Schaden von mehreren zehntausend Euro angerichtet. Warum das Feuer, das gegen 22.30 Uhr gemeldet wurde, ausbrach, ist derweil noch unklar. Als Kr&auml;fte ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-15\">15.06.2026<\/time> &middot; <a href=\"\/news\/braende-offenbach-am-main\" title=\"Br\u00e4nde Offenbach am Main\">Feuerwehr<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/roedermark-aktuell\" title=\"R\u00f6dermark heute aktuell\">R\u00f6dermark<\/a> &middot; <\/span><a href=\"https:\/\/www.rheinmainverlag.de\/2026\/06\/15\/feuer-in-leerstehendem-haus-in-roedermark\/\" title=\"Link zum Artikel auf rheinmainverlag.de\" target=\"_blank\">rheinmainverlag.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"de145071\" href=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/gewerbekontrolle-illegales-lachgas-snus-vapes-und-sogar-spielautomat-sichergestellt\/\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf dreieich.de\" target=\"_blank\">Gewerbekontrolle: Illegales Lachgas, Snus, Vapes und sogar Spielautomat sichergestellt<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/gewerbekontrolle-illegales-lachgas-snus-vapes-und-sogar-spielautomat-sichergestellt\/\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/gewerbekontrolle-illegales-lachgas-snus-vapes-und-sogar-spielautomat-sichergestellt\/080-gewerbekontrolle.jpg?cid=1siq.8e12&resize=092b4c%3a1024x768c\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Am Freitag, den 12. Juni, f&uuml;hrten die Stadtpolizei Dreieich, die Landespolizei Hessen, die Kontrolleinheit Verkehrswege des Hauptzollamtes Darmstadt sowie das Gewerbeamt der Stadt Dreieich in der Zeit von 18 bis 24 Uhr eine gemeinsame Gro&szlig;kontrolle im Stadtgebiet ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-15\">15.06.2026<\/time> &middot; <a href=\"\/news\/dreieich-aktuell\" title=\"Dreieich heute aktuell\">Dreieich<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.dreieich.de\/rathaus-service\/presse-medien\/pressemitteilungen\/2026\/gewerbekontrolle-illegales-lachgas-snus-vapes-und-sogar-spielautomat-sichergestellt\/\" title=\"Link zum Artikel auf dreieich.de\" target=\"_blank\">dreieich.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"5239d822\" href=\"https:\/\/www.op-online.de\/offenbach\/von-veranstaltungsort-drogen-razzia-in-offenbach-geschaeftsfuehrer-sorgt-sich-um-ruf-94351745.html\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">Drogen-Kontrolle bei Offenbacher Events: Veranstalter sorgt sich um Ruf der Location<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.op-online.de\/offenbach\/von-veranstaltungsort-drogen-razzia-in-offenbach-geschaeftsfuehrer-sorgt-sich-um-ruf-94351745.html\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.op-online.de\/assets\/images\/42\/959\/42959533-polizei-Gef.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   Drogenfund in 16 F&auml;llen: In Offenbach untersucht die Polizei die G&auml;ste von Techno-Partys. Ein Veranstalter macht sich Sorgen.<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-15\">15.06.2026<\/time> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.op-online.de\/offenbach\/von-veranstaltungsort-drogen-razzia-in-offenbach-geschaeftsfuehrer-sorgt-sich-um-ruf-94351745.html\" title=\"Link zum Artikel auf op-online.de\" target=\"_blank\">op-online.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"0441d404\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">Polizei Offenbach am Main: Pressemeldungen vom 15.06.2026<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   ... <b>1. Unbekannter schlug auf drei M\u00e4nner ein: Zeugen gesucht! - Neu-Isenburg<\/b>   (cb) Nachdem es am Freitag, gegen 2.45 Uhr, zu einer k\u00f6rperlichen Auseinandersetzung kam, bei der drei Personen verletzt wurden, suchen die Ermittler der Kripo nach Zeugen der Tat. Ein 42-J\u00e4hriger war nach ersten Erkenntnissen mit seinen zwei Begleitern auf ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>2. Hakenkreuze in Unterf\u00fchrung festgestellt - Heusenstamm<\/b>   (cb) Ein Mitteiler informierte am Samstagvormittag die Beamten der Polizeistation Heusenstamm \u00fcber ein Hakenkreuz in der Unterf\u00fchrung der Jahnstra\u00dfe. Unbekannte hatten dieses mit schwarzer Farbe aufgespr\u00fcht und dadurch einen Sachschaden von etwa 250 Euro ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>3. Wer hat den Roller in Brand gesteckt? - Dietzenbach<\/b>   (cb) Wer hat den Roller in Brand gesteckt und dadurch einen Sachschaden von ungef\u00e4hr 1.500 Euro verursacht? Das fragen sich die Ermittler der Kripo in Offenbach und suchen Zeugen der Tat. Diese ereignete sich am Samstag, gegen 22.10 Uhr, in der Limesstra\u00dfe, ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>4. Zeugen gesucht! VW geklaut - M\u00fchlheim am Main<\/b>   (cb) Autodiebe hatten es auf einen VW Amarok abgesehen, der in der Hanauer Stra\u00dfe (einstellige Hausnummern) abgestellt war. Der Fahrzeugeigent\u00fcmer parkte seinen grauen Wagen mit OF-Kennzeichen am Donnerstag, gegen 22 Uhr, am Fahrbahnrand. Als er am Folgetag, ...<br clear=\"all\" \/><\/p><p style=\"margin-top:8px; margin-bottom:4px;\"><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a> ... <b>5. Zeugensuche nach Auseinandersetzung in B\u00e4ckerei - Rodgau<\/b>   (cb) Ein etwa 50 Jahre alter Mann mit dunklem Vollbart und grau\/schwarzen nach hinten gek\u00e4mmten Haaren soll am Samstagmorgen in einen Streit in einer B\u00e4ckerei in der Oberen Marktstra\u00dfe (einstellige Hausnummern) involviert gewesen sein. Nach dem derzeitigen ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-15\">15.06.2026<\/time> &middot; <a href=\"\/news\/dietzenbach-aktuell\" title=\"Dietzenbach heute aktuell\">Dietzenbach<\/a> &middot; <a href=\"\/news\/heusenstamm-aktuell\" title=\"Heusenstamm heute aktuell\">Heusenstamm<\/a> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/muehlheim-aktuell\" title=\"M\u00fchlheim heute aktuell\">M\u00fchlheim<\/a> &middot; <a href=\"\/news\/neu-isenburg-aktuell\" title=\"Neu-Isenburg heute aktuell\">Neu-Isenburg<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <a href=\"\/news\/rodgau-aktuell\" title=\"Rodgau heute aktuell\">Rodgau<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294550\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n<div class=\"post\" style=\"margin-bottom:40px;\">\n <article>\n <h2><a name=\"90242f2d\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294690\" rel=\"bookmark\" style=\"color:#333333; font-weight:bold;\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">POL-OF: Taschendiebe in der Innenstadt aktiv: Polizei gibt Pr\u00e4ventionstipps<\/a><\/h2>\n <div class=\"entry\">\n  <p style=\"margin-bottom:4px;\">\n   <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294690\" target=\"_blank\"><img decoding=\"async\" src=\"\/feeds\/gfx\/POL-OF.jpg\" style=\"align:left !important; float:left !important; margin-top:4px !important; margin-right:8px !important; margin-bottom:4px !important; width:90px !important;\" \/><\/a>   (lei) Sie nutzen einen kurzen Moment der Unaufmerksamkeit, das Gedr\u00e4nge in Gesch\u00e4ften oder die Enge eines Fahrstuhls: Taschendiebe haben in den vergangenen Wochen in der Offenbacher Innenstadt wiederholt ihr Unwesen getrieben. Seit Mitte M\u00e4rz registrierte die ...<br clear=\"all\" \/>  <\/p>\n  <div><span class=\"my_article_details\"><time datetime=\"2026-06-15\">15.06.2026<\/time> &middot; <a href=\"\/news\/langen-aktuell\" title=\"Langen heute aktuell\">Langen<\/a> &middot; <a href=\"\/news\/offenbach-aktuell\" title=\"Offenbach heute aktuell\">Offenbach<\/a> &middot; <a href=\"\/news\/polizeieinsaetze-offenbach-am-main\" title=\"Polizeieins\u00e4tze Offenbach am Main\">Polizei<\/a> &middot; <\/span><a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43561\/6294690\" title=\"Link zum Artikel auf presseportal.de\" target=\"_blank\">presseportal.de<\/a><\/div>\n  <b><\/b>\n <\/div>\n <\/article>\n<\/div>\n\n<p>&nbsp;<\/p>\n<div><span class=\"my_article_details\"><a href=\"https:\/\/www.heusenstaemmchen.de\/news\/polizeieinsaetze-offenbach-am-main\"><b>Polizeieins\u00e4tze im Kreis Offenbach am Main<\/b><\/a>:<br \/>\n<a href=\"https:\/\/www.heusenstaemmchen.de\/news\/betrugsfaelle-offenbach-am-main\">Betrugsf\u00e4lle<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/braende-offenbach-am-main\">Br\u00e4nde<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/diebstaehle-offenbach-am-main\">Diebst\u00e4hle<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/einbrueche-offenbach-am-main\">Einbr\u00fcche<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/raubueberfaelle-offenbach-am-main\">Raub\u00fcberf\u00e4lle<\/a> &middot; <a href=\"https:\/\/www.heusenstaemmchen.de\/news\/unfaelle-offenbach-am-main\">Unf\u00e4lle<\/a><\/span><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aktuelle Polizeieins\u00e4tze im Kreis Offenbach am Main von heute und den letzten Wochen Betrugsf\u00e4lle &middot; Br\u00e4nde &middot; Diebst\u00e4hle &middot; Einbr\u00fcche &middot; Raub\u00fcberf\u00e4lle &middot; Unf\u00e4lle &nbsp; &nbsp; Polizeieins\u00e4tze im Kreis Offenbach am Main: Betrugsf\u00e4lle &middot; Br\u00e4nde &middot; Diebst\u00e4hle &middot; Einbr\u00fcche &middot; Raub\u00fcberf\u00e4lle &middot;&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":13343,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[477],"tags":[311,156,133,456,4,90,457,302,102,433,455,492,458,190,459],"class_list":["post-12755","page","type-page","status-publish","has-post-thumbnail","hentry","category-polizeiberichte","tag-dietzenbach","tag-dreieich","tag-egelsbach","tag-hainburg","tag-heusenstamm","tag-langen","tag-mainhausen","tag-muehlheim-am-main","tag-neu-isenburg","tag-obertshausen","tag-offenbach-am-main","tag-polizeieinsatz","tag-roedermark","tag-rodgau","tag-seligenstadt"],"_links":{"self":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/pages\/12755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/comments?post=12755"}],"version-history":[{"count":3,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/pages\/12755\/revisions"}],"predecessor-version":[{"id":13706,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/pages\/12755\/revisions\/13706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/media\/13343"}],"wp:attachment":[{"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/media?parent=12755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/categories?post=12755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.heusenstaemmchen.de\/news\/wp-json\/wp\/v2\/tags?post=12755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}